{"id":12109,"date":"2017-04-21T20:00:40","date_gmt":"2017-04-21T19:00:40","guid":{"rendered":"http:\/\/www.moyenagepassion.com\/?p=12109"},"modified":"2024-02-26T00:30:20","modified_gmt":"2024-02-25T23:30:20","slug":"jean-de-meung-rutebeuf-vacuite-des-richesses-et-biens-materiels-face-a-la-mort","status":"publish","type":"post","link":"https:\/\/www.moyenagepassion.com\/index.php\/2017\/04\/21\/jean-de-meung-rutebeuf-vacuite-des-richesses-et-biens-materiels-face-a-la-mort\/","title":{"rendered":"Jean de Meung : mauvaise conscience et inutilit\u00e9 des possessions au moment de la mort"},"content":{"rendered":"<div id=\"moyen-1288365824\" class=\"moyen-before-content moyen-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-3035390706780632\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-3035390706780632\" \ndata-ad-slot=\"\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><p style=\"text-align: left;\"><strong class=\"alignleft\"><img decoding=\"async\" class=\"wp-image-6797 alignleft\" src=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2016\/09\/citations_medievales_.jpg\" alt=\"citations_medievales_\" width=\"128\" height=\"128\" srcset=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2016\/09\/citations_medievales_.jpg 250w, https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2016\/09\/citations_medievales_-150x150.jpg 150w\" sizes=\"(max-width: 128px) 100vw, 128px\" \/><br \/>\n<\/strong> <strong>Sujet\u00a0<\/strong>: citation, sagesse m\u00e9di\u00e9vale, po\u00e9sie morale et satirique.<br \/>\n<strong>P\u00e9riode<\/strong> : Moyen \u00c2ge central<br \/>\n<strong>Auteur<\/strong> : Jean de Meung (Clopinel) (1250-1305) et Rutebeuf\u00a0(1230-1285?)<br \/>\n<strong>Ouvrage<\/strong> : le codicille<\/p>\n<p>Bonjour \u00e0 tous,<\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" class=\"alignleft size-full wp-image-162\" src=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2015\/12\/N_lettrine_moyen_age_passion.jpg\" alt=\"N_lettrine_moyen_age_passion\" width=\"84\" height=\"103\" \/>ous revenons, aujourd&rsquo;hui, sur le codicille de Jean de Meung, que l&rsquo;on trouve, la plupart du temps, annex\u00e9 aux \u00e9ditions du <em><strong>Roman de la rose<\/strong><\/em> dont il fut le co-auteur. Ce texte se pr\u00e9sente sous la forme d&rsquo;un po\u00e8me critique, un legs moral que l&rsquo;auteur m\u00e9di\u00e9val fait \u00e0 ses contemporains\u00a0: clercs, hommes de religions ou puissants, notamment, et dans lequel il n&rsquo;h\u00e9site pas \u00e0 les \u00e9gratigner ou les prendre \u00e0 partie.<\/p>\n<p><a href=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2017\/04\/citation_sagesse_medievale_jean_de_meung_codicille_moyen-age_central.jpg\"><img decoding=\"async\" class=\"alignnone size-full wp-image-12113\" src=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2017\/04\/citation_sagesse_medievale_jean_de_meung_codicille_moyen-age_central.jpg\" alt=\"citation_sagesse_medievale_jean_de_meung_codicille_moyen-age_central\" width=\"1200\" height=\"540\" srcset=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2017\/04\/citation_sagesse_medievale_jean_de_meung_codicille_moyen-age_central.jpg 1200w, https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2017\/04\/citation_sagesse_medievale_jean_de_meung_codicille_moyen-age_central-300x135.jpg 300w, https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2017\/04\/citation_sagesse_medievale_jean_de_meung_codicille_moyen-age_central-1024x461.jpg 1024w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #008000;\"><em><strong>\u00ab\u00a0Chascun scet que quant l&rsquo;ame de sa charoigne part,<\/strong><\/em><\/span><br \/>\n<span style=\"color: #008000;\"><em><strong> De ce monde n&#8217;emporte avec soy point de part;<\/strong><\/em><\/span><br \/>\n<span style=\"color: #008000;\"><em><strong> Sa desserte l&#8217;emmaine, bien ou mal s&rsquo;en d\u00e9part,<\/strong><\/em><\/span><br \/>\n<span style=\"color: #008000;\"><em><strong> En aussi pou de temps comme il tonne ou espart.<\/strong><\/em><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #008000;\"><strong><em>Pensons que quant ly homs est au travail de mort,<\/em><\/strong><\/span><br \/>\n<span style=\"color: #008000;\"><strong><em> Ses biens ne ses richesses ne luy valent que mort<\/em><\/strong><\/span><br \/>\n<span style=\"color: #008000;\"><strong><em> Ne luy peuvent oster l&rsquo;angoisse qui le mort,<\/em><\/strong><\/span><br \/>\n<span style=\"color: #008000;\"><strong><em> De ce dont conscience le reprent et remort\u00a0\u00bb<br \/>\n<\/em><\/strong><span style=\"color: #808080;\">Jean de Meung &#8211; Le Codicille<\/span><\/span><\/p>\n<p style=\"text-align: justify;\">Grand \u00e9rudit, critique et moraliste, <em><strong>Jean de Meung<\/strong><\/em> n&rsquo;en est pas \u00e0 son galop d&rsquo;essai pour ce qui est de manier la satire. Dans ce passage du codicille sur la conscience qui vient tourmenter le mourant sur son lit de douleur, il nous parlera tout \u00e0 la fois :<\/p>\n<ul>\n<li style=\"text-align: justify;\">de la vacuit\u00e9\u00a0de\u00a0l&rsquo;obsession d&rsquo;accumuler des biens mat\u00e9riels\u00a0et des richesses,\u00a0pire encore quand ils sont acquis de mani\u00e8re malhonn\u00eate (<em><strong>\u00ab\u00a0Bien mal acquis ne profite jamais\u00a0\u00bb<\/strong><\/em>)<\/li>\n<li style=\"text-align: justify;\">de ne pas transmettre \u00e0 des h\u00e9ritiers de telles richesses mal acquises, au risque de leur empoisonner la vie et de les vouer eux-m\u00eame \u00ab\u00a0aux enfers\u00a0\u00bb.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2016\/01\/rutebeuf_troubadour_trouverre_ppete_moyen-age.jpg\"><img decoding=\"async\" class=\"wp-image-1297 alignleft\" src=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2016\/01\/rutebeuf_troubadour_trouverre_ppete_moyen-age.jpg\" alt=\"rutebeuf_troubadour_trouverre_ppete_moyen-age\" width=\"163\" height=\"92\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Le th\u00e8me de la mauvaise conscience et des tourments qui se font jour face \u00e0 la mort, au sujet de ses propres inconduites, n&rsquo;est pas nouveau et reste cher au moyen-\u00e2ge. Nous sommes dans\u00a0\u00a0l&rsquo;Europe m\u00e9di\u00e9vale du XIIIe si\u00e8cle et\u00a0il est donc question ici de mettre en pratique les pr\u00e9ceptes de\u00a0morale et de conduite chr\u00e9tienne, sans attendre qu&rsquo;il soit trop tard : ce monde n&rsquo;est qu&rsquo;un passage et nous n\u2019emm\u00e8nerons rien dans l&rsquo;au-del\u00e0 que notre \u00e2me et nos actions pass\u00e9es.<\/p>\n<p style=\"text-align: justify;\">On retrouvera pratiquement ses vers \u00e0 l&rsquo;identique chez <em><strong>Rutebeuf<\/strong><\/em>, et au vue des dates, <em><strong>Jean de Meung<\/strong><\/em> s&rsquo;est certainement inspir\u00e9 directement du c\u00e9l\u00e8bre jongleur et trouv\u00e8re. Voici les vers de ce dernier, tir\u00e9s de son dit de la croisade de Tunis :<\/p>\n<p><span style=\"color: #008000;\"><em><strong>\u00ab\u00a0Vous vous moqueiz de Dieu tant que vient a la mort,<\/strong><\/em><\/span><br \/>\n<span style=\"color: #008000;\"><em><strong>Si li crieiz mercei lors que li mors vos mort<\/strong><\/em><\/span><br \/>\n<span style=\"color: #008000;\"><em><strong>Et une consciance vos reprent et remort ;<\/strong><\/em><\/span><br \/>\n<span style=\"color: #008000;\"><em><strong>Si n&rsquo;en souvient nelui tant que la mors le mort.\u00a0\u00bb<br \/>\n<\/strong><\/em><\/span><span style=\"color: #999999;\">Rutebeuf &#8211;\u00a0Le dit de la croisade de Tunis<\/span><\/p>\n<p><em>\u00ab\u00a0Vous vous moquez de Dieu jusqu&rsquo;\u00e0 l&rsquo;heure de la mort,<\/em><br \/>\n<em>et vous lui criez gr\u00e2ce lorsque la mort vous mord,<\/em><br \/>\n<em>que dans votre conscience sont reproches et remords;<\/em><br \/>\n<em>Nul n&rsquo;y pense jusqu&rsquo;au moment o\u00f9 la mort le mord.\u00a0\u00bb<\/em><br \/>\n<span style=\"color: #999999;\">Traduction de Michel Zink<\/span><\/p>\n<p style=\"text-align: justify;\">Pour \u00e9largir au del\u00e0 du moyen-\u00e2ge chr\u00e9tien occidental, dans nombre de cultures et de pratiques spirituelles, cultiver la conscience de sa propre impermanence et de sa propre mort est consid\u00e9r\u00e9, loin de toute forme de pens\u00e9es n\u00e9gatives ou morbides, comme un guide efficace dans les actions de la vie (leur intensit\u00e9, comme leur profondeur).<\/p>\n<p>En vous souhaitant une belle journ\u00e9e.<\/p>\n<p>Fred<br \/>\nPour moyenagepassion.com<br \/>\n<em><strong>A la d\u00e9couverte du monde m\u00e9di\u00e9val sous toutes ses formes.<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sujet\u00a0: citation, sagesse m\u00e9di\u00e9vale, po\u00e9sie morale et satirique. P\u00e9riode : Moyen \u00c2ge central Auteur : Jean de Meung (Clopinel) (1250-1305) et Rutebeuf\u00a0(1230-1285?) Ouvrage : le codicille Bonjour \u00e0 tous, ous revenons, aujourd&rsquo;hui, sur le codicille de Jean de Meung, que l&rsquo;on trouve, la plupart du temps, annex\u00e9 aux \u00e9ditions du Roman de la rose dont &hellip; <a href=\"https:\/\/www.moyenagepassion.com\/index.php\/2017\/04\/21\/jean-de-meung-rutebeuf-vacuite-des-richesses-et-biens-materiels-face-a-la-mort\/\" class=\"more-link\">Continuer la lecture de <span class=\"screen-reader-text\">Jean de Meung : mauvaise conscience et inutilit\u00e9 des possessions au moment de la mort<\/span>  <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"quote","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[154,2411,1490],"tags":[728,155,1580,1579,22,182,18,85,615,688,294,622,295,165,449,687],"class_list":["post-12109","post","type-post","status-publish","format-quote","hentry","category-citations-moyen-age-medievales","category-jean-de-meung","category-rutebeuf","tag-auteur-medieval","tag-citation","tag-jean-clopinel","tag-jean-de-meung","tag-medievale","tag-monde-medieval","tag-moyen-age","tag-moyen-age-central","tag-poesie-medievale","tag-poesie-satirique","tag-poete","tag-poete-medieval","tag-rutebeuf","tag-sagesse","tag-sagesse-medievale","tag-satire","post_format-post-format-quote"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/posts\/12109"}],"collection":[{"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/comments?post=12109"}],"version-history":[{"count":4,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/posts\/12109\/revisions"}],"predecessor-version":[{"id":49899,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/posts\/12109\/revisions\/49899"}],"wp:attachment":[{"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/media?parent=12109"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/categories?post=12109"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/tags?post=12109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}