{"id":15843,"date":"2017-09-22T04:27:06","date_gmt":"2017-09-22T03:27:06","guid":{"rendered":"http:\/\/www.moyenagepassion.com\/?p=15843"},"modified":"2020-10-04T21:21:22","modified_gmt":"2020-10-04T20:21:22","slug":"le-chateau-bourguignon-des-bordes-fait-ses-medievales-en-grand","status":"publish","type":"post","link":"https:\/\/www.moyenagepassion.com\/index.php\/2017\/09\/22\/le-chateau-bourguignon-des-bordes-fait-ses-medievales-en-grand\/","title":{"rendered":"Le ch\u00e2teau bourguignon des Bordes f\u00eate ses m\u00e9di\u00e9vales en grand"},"content":{"rendered":"<div id=\"moyen-2808990363\" class=\"moyen-before-content moyen-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-3035390706780632\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-3035390706780632\" \ndata-ad-slot=\"\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><p><strong><a href=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2017\/09\/agenda_fetes_compagnies_medievales_sorties_historique_chateau_des_bordes_bourgogne.jpg\"><img decoding=\"async\" class=\"wp-image-15862 alignleft\" src=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2017\/09\/agenda_fetes_compagnies_medievales_sorties_historique_chateau_des_bordes_bourgogne.jpg\" alt=\"agenda_fetes_compagnies_medievales_sorties_historique_chateau_des_bordes_bourgogne\" width=\"152\" height=\"237\" srcset=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2017\/09\/agenda_fetes_compagnies_medievales_sorties_historique_chateau_des_bordes_bourgogne.jpg 497w, https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2017\/09\/agenda_fetes_compagnies_medievales_sorties_historique_chateau_des_bordes_bourgogne-192x300.jpg 192w\" sizes=\"(max-width: 152px) 100vw, 152px\" \/><\/a>Sujet<\/strong>\u00a0: \u00a0f\u00eates, animations, m\u00e9di\u00e9vales, mesnies et compagnies m\u00e9di\u00e9vales, march\u00e9 m\u00e9di\u00e9val, joute, tournoi de chevaliers, escrime ancienne, archerie.<br \/>\n<strong>Lieu<\/strong>\u00a0:\u00a0<a href=\"http:\/\/www.chateaudesbordes.net\/\" target=\"_blank\" rel=\"noopener noreferrer\">Ch\u00e2teau des Bordes<\/a>,\u00a0Urzy, Ni\u00e8vre, Bourgogne-Franche-Comt\u00e9<br \/>\n<strong>Ev\u00e9nement<\/strong>\u00a0: Les m\u00e9di\u00e9vales du ch\u00e2teau des Bordes<em><strong><br \/>\n<\/strong><\/em><strong>Dates<\/strong>\u00a0: samedi 23 &amp; dimanche 24 septembre 2017<\/p>\n<p style=\"text-align: justify;\">Bonjour \u00e0 tous,<\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" class=\"alignleft size-full wp-image-394\" src=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2015\/12\/Q_lettrine_moyen_age_passion.jpg\" alt=\"Q_lettrine_moyen_age_passion\" width=\"96\" height=\"103\" \/>uand une historienne de l&rsquo;art, attach\u00e9e au Mus\u00e9e du Louvre et un architecte du patrimoine, n\u00e9cessairement f\u00e9rus\u00a0d&rsquo;Histoire, se piquent de passion pour les vieilles pierres d&rsquo;un ch\u00e2teau et d\u00e9cident de le restaurer, quand, en plus, pour accompagner cet ambitieux projet, d\u00e9but\u00e9 en 2014, le couple d\u00e9cide d&rsquo;organiser des \u00e9v\u00e9nements \u00e0 th\u00e8me de haute qualit\u00e9, alors nous ne pouvons que leur rendre deux fois gr\u00e2ce <a href=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2017\/09\/fetes_animations_medievales_chateau_des_bordes_bourgogne_nievre.jpg\"><img decoding=\"async\" class=\" wp-image-15880 alignright\" src=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2017\/09\/fetes_animations_medievales_chateau_des_bordes_bourgogne_nievre.jpg\" alt=\"fetes_animations_medievales_chateau_des_bordes_bourgogne_nievre\" width=\"222\" height=\"312\" srcset=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2017\/09\/fetes_animations_medievales_chateau_des_bordes_bourgogne_nievre.jpg 450w, https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2017\/09\/fetes_animations_medievales_chateau_des_bordes_bourgogne_nievre-213x300.jpg 213w\" sizes=\"(max-width: 222px) 100vw, 222px\" \/><\/a>et vous inviter, du m\u00eame coup, \u00e0 vous pencher de plus pr\u00e8s sur leur programme d&rsquo;activit\u00e9s et notamment sur celle qu&rsquo;ils ont concoct\u00e9e pour\u00a0cette fin de semaine.<\/p>\n<p style=\"text-align: justify;\">Situ\u00e9\u00a0dans la Ni\u00e8vre, \u00e0 quelques lieues au nord de Nevers et \u00e0 quelques encablures \u00e0 l&rsquo;est de Bourges, \u00a0le ch\u00e2teau des Bordes, car c&rsquo;est de lui qu&rsquo;il s&rsquo;agit, vous propose donc ce week-end une belle\u00a0f\u00eate m\u00e9di\u00e9vale de deux jours\u00a0pleins. Il s&rsquo;agit d&rsquo;une premi\u00e8re mais ne vous y trompez pas, les choses ont \u00e9t\u00e9 faites en grand et cet \u00e9v\u00e9nement s&rsquo;annonce d\u00e9j\u00e0 comme un de ceux sur lesquels il faudra d\u00e9sormais compter en Bourgogne-Franche-Comt\u00e9.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2017\/09\/fetes_agenda_animations_medievales_chateau_des_bordes_bourgogne_nievre.jpg\"><img decoding=\"async\" class=\"alignnone size-full wp-image-15859\" src=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2017\/09\/fetes_agenda_animations_medievales_chateau_des_bordes_bourgogne_nievre.jpg\" alt=\"fetes_agenda_animations_medievales_chateau_des_bordes_bourgogne_nievre\" width=\"806\" height=\"681\" srcset=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2017\/09\/fetes_agenda_animations_medievales_chateau_des_bordes_bourgogne_nievre.jpg 806w, https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2017\/09\/fetes_agenda_animations_medievales_chateau_des_bordes_bourgogne_nievre-300x253.jpg 300w\" sizes=\"(max-width: 806px) 100vw, 806px\" \/><\/a><\/p>\n<h2 style=\"text-align: justify;\">Un programme d&rsquo;exception<\/h2>\n<p style=\"text-align: justify;\"><img decoding=\"async\" class=\"alignleft size-full wp-image-162\" src=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2015\/12\/N_lettrine_moyen_age_passion.jpg\" alt=\"N_lettrine_moyen_age_passion\" width=\"84\" height=\"103\" \/>ombre de campements \u00e0 la d\u00e9couverte de la vie au moyen-\u00e2ge et \u00e0 la rencontre des passionn\u00e9s d&rsquo;histoire vivante venus se joindre \u00e0 la f\u00eate, march\u00e9 artisanal et m\u00e9di\u00e9val avec pr\u00e8s de quarante cinq \u00e9choppes, \u00a0il y aura encore, ce week end, au ch\u00e2teau des Bordes, un village d&rsquo;artisanat ancien sp\u00e9cialement reconstitu\u00e9 pour l&rsquo;occasion, avec force d\u00e9monstrations de savoir-faire, en provenance du moyen-\u00e2ge : \u00a0calligraphie, enluminure, ferronnerie, taille de pierre, poterie, tourneur sur bois et de nombreux autres encore. \u00a0On comptera \u00e9galement, dans ce village m\u00e9di\u00e9val, sur la pr\u00e9sence d&rsquo;une\u00a0authentique ferme\u00a0d&rsquo;\u00e9poque qui saura, \u00e0 coup s\u00fbr, ravir les enfants !<\/p>\n<h3 style=\"text-align: justify;\"><strong>De nombreuses compagnies m\u00e9di\u00e9vales, artistes et<\/strong><strong>\u00a0mesnies pour animer la f\u00eate\u00a0<\/strong><\/h3>\n<p style=\"text-align: justify;\">Du point de vue des spectacles et des animations, rien ne manque et la liste est m\u00eame repl\u00e8te : \u00a0championnat national de joutes \u00e0 pied, tournoi d&rsquo;archerie, tournoi de chevalerie, tournoi et combats \u00e0 la fa\u00e7on viking, spectacles de fauconnerie, bateleurs, jongleurs, saltimbanques, m\u00e9nestrels, danseurs et <img decoding=\"async\" class=\" wp-image-15864 alignright\" src=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2017\/09\/agenda_fetes_compagnies_medievales_spectacle_feu_fokus_chateau_des_bordes_bourgogne.jpg\" alt=\"agenda_fetes_compagnies_medievales_spectacle_feu_fokus_chateau_des_bordes_bourgogne\" width=\"227\" height=\"354\" srcset=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2017\/09\/agenda_fetes_compagnies_medievales_spectacle_feu_fokus_chateau_des_bordes_bourgogne.jpg 497w, https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2017\/09\/agenda_fetes_compagnies_medievales_spectacle_feu_fokus_chateau_des_bordes_bourgogne-192x300.jpg 192w\" sizes=\"(max-width: 227px) 100vw, 227px\" \/>conteurs, il y aura m\u00eame des jeux en provenance d&rsquo;Ecosse et du lancer de troncs !<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008000;\"><em>La Seigneurie de Lisle &#8211; la\u00a0Mesnie du lion et de l&rsquo;hermine &#8211; la Mesnie du Gruchet &#8211; Saor Alba &#8211; la Mesnie du Renard &#8211; les R\u00f4deurs de l&rsquo;Odan &#8211; l&rsquo;Amici d&rsquo;Orbais &#8211; Steamedvik &#8211; Bernard Legris &#8211; le Village en torchis &#8211; No\u00ebl Vernois &#8211; la Cie de Saint-Ouen &#8211; la Milice marchande du Bugey &#8211; le Chardon \u00e9cossais &#8211; la Horde des Mondes oubli\u00e9s &#8211; Cie Fokus &#8211; Les\u00a0R&rsquo;montemps, &#8211; \u00a0La Cie du Rohan &#8211;\u00a0 les\u00a0<em>Archers de Saint-Martin\u00a0&#8211;\u00a0Managarm Vikingar\u00a0&#8211; Armoria\u00a0et le\u00a0<em>H\u00e9risson \u00e0 plumes &#8211; Dagobert &#8211; \u00a0Thomas Fradin\u00a0 vieilliste &#8211;\u00a0<em>Olivier Stojmirovic<\/em><\/em><\/em><\/em><\/span><\/p>\n<p style=\"text-align: justify;\">Temps fort de ces m\u00e9di\u00e9vales, un grand banquet anim\u00e9 sera donn\u00e9 le samedi soir,\u00a0suivi d&rsquo;un\u00a0spectacle pyrotechnique et \u00e9questre.<\/p>\n<h3 style=\"text-align: justify;\"><strong>Ripailles et \u00a0f\u00eate de la Gastronomie 2017<\/strong><\/h3>\n<p style=\"text-align: justify;\">Ajoutons encore que du c\u00f4t\u00e9 des ripailles, <em><strong>Les M\u00e9di\u00e9vales du ch\u00e2teau des Bordes<\/strong>\u00a0<\/em>comptent parmi les c\u00e9l\u00e9brations<em>\u00a0<\/em>retenues au titre de la <em><strong>f\u00eate de la Gastronomie 2017, <\/strong><\/em>lanc\u00e9e \u00e0 l&rsquo;initiative du Minist\u00e8re de la Culture. Entre le banquet du samedi soir, le pain cuit \u00e0 l&rsquo;ancienne au four (r\u00e9cemment restaur\u00e9) du ch\u00e2teau et les pr\u00e8s de dix \u00e9choppes du march\u00e9 qui vous proposeront des recettes aux\u00a0saveurs m\u00e9di\u00e9vales, il y aura, \u00e0 l&rsquo;\u00e9vidence, sur place, largement de quoi vous r\u00e9galer en quantit\u00e9 mais aussi en qualit\u00e9!<\/p>\n<div class=\"text_exposed_show\">\n<p><a href=\"http:\/\/www.chateaudesbordes.net\/uploads\/6\/1\/1\/4\/61148605\/programme.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Tout le programme des m\u00e9di\u00e9vales du Ch\u00e2teau des Bordes<\/a><\/p>\n<\/div>\n<h2>Le Ch\u00e2teau des Bordes, du ch\u00e2teau-fort m\u00e9di\u00e9val au palais renaissant du XVIIe<\/h2>\n<p style=\"text-align: justify;\"><span style=\"color: #008000;\"><strong><em>\u00ab\u00a0Dans la riante vall\u00e9e de la Ni\u00e8vre, et sur le sommet d&rsquo;un coteau, qui domine \u00e0 l&rsquo;est le paisible village d&rsquo;Urzy, situ\u00e9 \u00e0 deux lieues de Nevers, s&rsquo;\u00e9l\u00e8ve l&rsquo;ancien ch\u00e2teau des Bordes, l&rsquo;un des plus beaux du Nivernais. Ses tours aux cr\u00e9neaux et aux m\u00e2chicoulis sans nombre, aux toits d&rsquo;ardoises orgueilleusement jet\u00e9s dans l&rsquo;espace, ses tourelles et sa coquette vigie, en un mot l&rsquo;ensemble et l&rsquo;aspect de ses constructions offrent un spectacle imposant pour une\u00a0imagination, lorsque venant de Nevers, soit par le Pont-Saint-Ours, soit par les bois d&rsquo;Urzy, il se d\u00e9couvre grandiose et majestueux aux yeux \u00e9tonn\u00e9s du voyageur.\u00a0\u00bb<br \/>\n<\/em><\/strong><span style=\"color: #808080;\"><em>Le ch\u00e2teau de Bordes et ses seigneurs, Adrien Bonvallet,\u00a01869<\/em><\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" class=\"alignleft size-full wp-image-36\" src=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2015\/12\/C_lettrine_moyen_age_passion.jpg\" alt=\"C_lettrine_moyen_age_passion\" width=\"84\" height=\"103\" \/>omment servir une meilleure introduction \u00e0 ce beau monument historique class\u00e9 depuis 1946 que ces quelques lignes que l&rsquo;historien et arch\u00e9ologue\u00a0<em><strong>Adrien Bonvallet<\/strong><\/em> lui d\u00e9diait au XIXe si\u00e8cle ?\u00a0A l&rsquo;aube du moyen-\u00e2ge central, le site qui domine depuis ses hauteurs la plaine de la Ni\u00e8vre et garde un oeil sur la route de\u00a0Bourgogne, est occup\u00e9 par une famille alors puissante, les <em><strong>Bordes<\/strong><\/em>.\u00a0Un\u00a0premier ch\u00e2teau-fort y sera\u00a0\u00e9rig\u00e9, pr\u00e9s du milieu du \u00a0XIe si\u00e8cle (en 1041) par <em><strong>Jehan de Bordes<\/strong><\/em>,\u00a0chambellan de France. L&rsquo;\u00e9difice restera aux mains de cette maison jusqu&rsquo;au XVe si\u00e8cle.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2017\/09\/heraldique_blason_armoirie_Bourdillon_de_la_Platiere_chateau_bordes.jpg\"><img decoding=\"async\" class=\"wp-image-15874 alignright\" src=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2017\/09\/heraldique_blason_armoirie_Bourdillon_de_la_Platiere_chateau_bordes.jpg\" alt=\"heraldique_blason_armoirie_Bourdillon_de_la_Platiere_chateau_bordes\" width=\"135\" height=\"133\" srcset=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2017\/09\/heraldique_blason_armoirie_Bourdillon_de_la_Platiere_chateau_bordes.jpg 566w, https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2017\/09\/heraldique_blason_armoirie_Bourdillon_de_la_Platiere_chateau_bordes-300x296.jpg 300w\" sizes=\"(max-width: 135px) 100vw, 135px\" \/><\/a>D\u00e9truit en grande partie durant la guerre de cent ans, il ne subsistera gu\u00e8re de la premi\u00e8re forteresse que la tour Jeanne d&rsquo;Arc et le ch\u00e2teau fera l&rsquo;objet d&rsquo;une reconstruction \u00e0 la fin du XVe, sur ordonnance de\u00a0<em><strong>Charles VIII.\u00a0<\/strong><\/em>On y \u00e9difiera alors tours et donjon, pont-levis, foss\u00e9s et poterne en lui conservant, \u00e0 l&rsquo;\u00e9vidence, sa dimension d\u00e9fensive.\u00a0Au milieu du XVIe, de nouveaux travaux y seront entrepris donnant cette fois au b\u00e2timent, de fi\u00e8res allures de palais renaissant. Le site sera alors pass\u00e9\u00a0par les jeux de dots et d&rsquo;h\u00e9ritages aux mains de la puissante famille des\u00a0<em><strong>La Plati\u00e8re<\/strong><\/em> <span style=\"color: #808080;\">(voir armoiries ci-dessus)<\/span>, proches \u00e0 la fois de la couronne de France et du Duc d&rsquo;Orl\u00e9ans.<\/p>\n<p style=\"text-align: justify;\">Un si\u00e8cle plus tard, \u00a0<em><strong>Louis II d&rsquo;Ancienville<\/strong><\/em>, conseiller royal, ayant \u00e0 son tour h\u00e9rit\u00e9 du ch\u00e2teau par son p\u00e8re et par le\u00a0jeu des lignages et des \u00e9pousailles, apportera sa\u00a0touche personnelle \u00e0 l&rsquo;\u00e9difice \u00a0avec \u00a0de nombreux am\u00e9nagements parmi lesquels on pourra compter, entre autres, de grands\u00a0<a href=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2017\/09\/Marie_Casimire_Sobieski_reine_de_pologne.jpg\"><img decoding=\"async\" class=\"wp-image-15876 alignleft\" src=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2017\/09\/Marie_Casimire_Sobieski_reine_de_pologne.jpg\" alt=\"Marie_Casimire_Sobieski_reine_de_pologne\" width=\"184\" height=\"233\" srcset=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2017\/09\/Marie_Casimire_Sobieski_reine_de_pologne.jpg 362w, https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2017\/09\/Marie_Casimire_Sobieski_reine_de_pologne-237x300.jpg 237w\" sizes=\"(max-width: 184px) 100vw, 184px\" \/><\/a>vergers et potagers, quelques \u00e9difices et d\u00e9pendances suppl\u00e9mentaires\u00a0et, encore, de grandes \u00e9curies. Il dotera \u00e9galement les plus belles pi\u00e8ces du ch\u00e2teau de somptueuses d\u00e9corations entre chemin\u00e9es monumentales, peintures murales et belles fa\u00efences.\u00a0\u00a0C&rsquo;est dans le courant de ce m\u00eame si\u00e8cle que\u00a0la petite fille de ce dernier,\u00a0<strong>Marie de La Grange d&rsquo;Arquian, <\/strong>ajoutera au ch\u00e2teau une galerie de portraits de souverains polonais, et agrandira aussi les \u00e9curies, en leur donnant leur dimension royale, pour y accueillir l&rsquo;\u00e9quipage de sa soeur, devenue reine de Pologne, <em><strong>Marie-Casimire Sobieski\u00a0<\/strong><\/em><span style=\"color: #808080;\">(portrait ci-contre de Jean Tricius, 1676)<\/span><\/p>\n<p style=\"text-align: justify;\">Aux si\u00e8cles suivants, l&rsquo;\u00e9difice, comme tant d&rsquo;autres dans le courant des XVIIIe et XIXe, changera plusieurs fois de propri\u00e9taires sans que son entretien soit vraiment assur\u00e9. Il faudra attendre le milieu du XXe pour qu&rsquo;il soit class\u00e9 et notamment, les propri\u00e9taires actuels, <em><strong>Monsieur et Madame Matthieu Joulie<\/strong><\/em> pour que des s\u00e9rieuses campagnes de restauration y soient engag\u00e9es, Vous pouvez valablement consulter cette page pour en savoir plus sur les travaux qu&rsquo;ils y \u00a0ont engag\u00e9s :<a href=\"http:\/\/www.chateaudesbordes.net\/les-travaux.html\" target=\"_blank\" rel=\"noopener noreferrer\">\u00a0campagne actuelle de restauration du ch\u00e2teau des Bordes<\/a>.<\/p>\n<p style=\"text-align: justify;\">Il va de soi qu&rsquo;en vous rendant \u00e0 ces belles m\u00e9di\u00e9vales, qui encore une fois, s&rsquo;annoncent comme une f\u00eate de taille et de qualit\u00e9, vous ferez en quelque sorte coup double, en partageant un peu de leur passion et en les soutenant dans\u00a0ce grand projet qu&rsquo;ils ont d\u00e9cid\u00e9 d&rsquo;entreprendre.<\/p>\n<p style=\"text-align: justify;\">Avant de vous laisser, j&rsquo;ajoute que sur place, vous pourrez visiter l&rsquo;exposition des <a href=\"https:\/\/www.moyenagepassion.com\/index.php\/2017\/08\/31\/exposition-invitation-au-reve-les-belles-maquettes-medievales-de-pascale-laine\/\" target=\"_blank\" rel=\"noopener noreferrer\">superbes maquettes m\u00e9di\u00e9vales de Pascale Lain\u00e9<\/a>.<\/p>\n<p style=\"text-align: justify;\">En vous souhaitant une excellente journ\u00e9e.<\/p>\n<p>Fr\u00e9d\u00e9ric EFFE<br \/>\nPour moyenagepassion.com<br \/>\n<em><strong>A la d\u00e9couverte du moyen-\u00e2ge sous toutes ses formes.<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sujet\u00a0: \u00a0f\u00eates, animations, m\u00e9di\u00e9vales, mesnies et compagnies m\u00e9di\u00e9vales, march\u00e9 m\u00e9di\u00e9val, joute, tournoi de chevaliers, escrime ancienne, archerie. Lieu\u00a0:\u00a0Ch\u00e2teau des Bordes,\u00a0Urzy, Ni\u00e8vre, Bourgogne-Franche-Comt\u00e9 Ev\u00e9nement\u00a0: Les m\u00e9di\u00e9vales du ch\u00e2teau des Bordes Dates\u00a0: samedi 23 &amp; dimanche 24 septembre 2017 Bonjour \u00e0 tous, uand une historienne de l&rsquo;art, attach\u00e9e au Mus\u00e9e du Louvre et un architecte du patrimoine, &hellip; <a href=\"https:\/\/www.moyenagepassion.com\/index.php\/2017\/09\/22\/le-chateau-bourguignon-des-bordes-fait-ses-medievales-en-grand\/\" class=\"more-link\">Continuer la lecture de <span class=\"screen-reader-text\">Le ch\u00e2teau bourguignon des Bordes f\u00eate ses m\u00e9di\u00e9vales en grand<\/span>  <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[11,13],"tags":[3131,1391,2529,19,3129,212,3130,3132,1438,22,1227,2682,230,18,1536,3133,2772],"class_list":["post-15843","post","type-post","status-publish","format-standard","hentry","category-fetes-medievales-evenement","category-lieux-moyen-age-medievaux","tag-adrien-bonvallet","tag-agenda","tag-animations-medievales","tag-chateau","tag-chateau-des-bordes","tag-compagnies-medievales","tag-jehan-de-bordes","tag-louis-ii-dancienville","tag-marche","tag-medievale","tag-medievales","tag-medievales-2017","tag-monument-historique","tag-moyen-age","tag-patrimoine","tag-seigneurs-de-bordes","tag-sorties-historiques"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/posts\/15843"}],"collection":[{"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/comments?post=15843"}],"version-history":[{"count":1,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/posts\/15843\/revisions"}],"predecessor-version":[{"id":34385,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/posts\/15843\/revisions\/34385"}],"wp:attachment":[{"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/media?parent=15843"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/categories?post=15843"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/tags?post=15843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}