{"id":16844,"date":"2017-11-08T02:00:18","date_gmt":"2017-11-08T01:00:18","guid":{"rendered":"http:\/\/www.moyenagepassion.com\/?p=16844"},"modified":"2020-10-05T01:21:26","modified_gmt":"2020-10-05T00:21:26","slug":"le-moyen-age-de-jacques-le-goff","status":"publish","type":"post","link":"https:\/\/www.moyenagepassion.com\/index.php\/2017\/11\/08\/le-moyen-age-de-jacques-le-goff\/","title":{"rendered":"Le moyen-\u00e2ge de jacques le Goff"},"content":{"rendered":"<div id=\"moyen-1327163666\" class=\"moyen-before-content moyen-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-3035390706780632\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-3035390706780632\" \ndata-ad-slot=\"\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><p><strong>Sujet<\/strong> : citations, monde m\u00e9di\u00e9val, moyen-\u00e2ge, Histoire m\u00e9di\u00e9vale.<br \/>\n<strong>Auteur<\/strong> : Jacques le Goff\u00a0\u00a0(1924-2014), historien m\u00e9di\u00e9viste.<\/p>\n<p><a href=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2017\/11\/citation_monde_medieval_jacques_le_goff_historien_medieviste_moyen-age_racines_modernite.jpg\"><img decoding=\"async\" class=\"alignnone size-full wp-image-16845\" src=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2017\/11\/citation_monde_medieval_jacques_le_goff_historien_medieviste_moyen-age_racines_modernite.jpg\" alt=\"citation_monde_medieval_jacques_le_goff_historien_medieviste_moyen-age_racines_modernite\" width=\"1280\" height=\"481\" srcset=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2017\/11\/citation_monde_medieval_jacques_le_goff_historien_medieviste_moyen-age_racines_modernite.jpg 1280w, https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2017\/11\/citation_monde_medieval_jacques_le_goff_historien_medieviste_moyen-age_racines_modernite-300x113.jpg 300w, https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2017\/11\/citation_monde_medieval_jacques_le_goff_historien_medieviste_moyen-age_racines_modernite-1024x385.jpg 1024w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #008000;\"><em><strong>\u201cLe Moyen Age a \u00e9t\u00e9 un grand laboratoire d&rsquo;id\u00e9es, d&rsquo;institutions, de formes, et il reste une mine d&rsquo;enseignements. Il vient certes apr\u00e8s l&rsquo;Antiquit\u00e9, si riche, si florissante. Pourtant, malgr\u00e9 les progr\u00e8s de l&rsquo;histoire ancienne, les civilisations du pass\u00e9 ont pris un coup de vieux, d\u00fb sans doute \u00e0 l&rsquo;abandon du grec et du latin dans l&rsquo;enseignement. Les H\u00e9rodote, Salluste et autres Cic\u00e9ron ne sont plus nos anc\u00eatres : c&rsquo;est le Moyen Age qui, en se rapprochant, est devenu notre Antiquit\u00e9, nos sources, notre jeunesse.\u201d <\/strong><\/em><\/span><\/p>\n<p><span style=\"color: #808080;\">Jacques Le GOFF, historien m\u00e9di\u00e9viste (1924-2014) <\/span><br \/>\n<span style=\"color: #808080;\"><a style=\"color: #808080;\" href=\"http:\/\/www.telerama.fr\/livre\/jacques-le-goff-le-confesseur-du-moyen-age,110634.php\" target=\"_blank\" rel=\"noopener noreferrer\">Extrait d\u2019un entretien de 1999 (T\u00e9l\u00e9rama)<\/a><\/span><\/p>\n<p>En vous souhaitant une belle journ\u00e9e.<\/p>\n<p>Fred<br \/>\nPour moyenagepassion.com<br \/>\nA la d\u00e9couverte du moyen-\u00e2ge sous toutes ses formes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sujet : citations, monde m\u00e9di\u00e9val, moyen-\u00e2ge, Histoire m\u00e9di\u00e9vale. Auteur : Jacques le Goff\u00a0\u00a0(1924-2014), historien m\u00e9di\u00e9viste. \u201cLe Moyen Age a \u00e9t\u00e9 un grand laboratoire d&rsquo;id\u00e9es, d&rsquo;institutions, de formes, et il reste une mine d&rsquo;enseignements. Il vient certes apr\u00e8s l&rsquo;Antiquit\u00e9, si riche, si florissante. Pourtant, malgr\u00e9 les progr\u00e8s de l&rsquo;histoire ancienne, les civilisations du pass\u00e9 ont pris &hellip; <a href=\"https:\/\/www.moyenagepassion.com\/index.php\/2017\/11\/08\/le-moyen-age-de-jacques-le-goff\/\" class=\"more-link\">Continuer la lecture de <span class=\"screen-reader-text\">Le moyen-\u00e2ge de jacques le Goff<\/span>  <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"quote","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[154],"tags":[155,520,182,18],"class_list":["post-16844","post","type-post","status-publish","format-quote","hentry","category-citations-moyen-age-medievales","tag-citation","tag-histoire-medievale","tag-monde-medieval","tag-moyen-age","post_format-post-format-quote"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Sujet : citations, monde m\u00e9di\u00e9val, moyen-\u00e2ge, Histoire m\u00e9di\u00e9vale. Auteur : Jacques le Goff (1924-2014), historien m\u00e9di\u00e9viste. \u201cLe Moyen Age a \u00e9t\u00e9 un grand laboratoire d&#039;id\u00e9es, d&#039;institutions, de formes, et il reste une mine d&#039;enseignements. Il vient certes apr\u00e8s l&#039;Antiquit\u00e9, si riche, si florissante. Pourtant, malgr\u00e9 les progr\u00e8s de l&#039;histoire ancienne, les civilisations du pass\u00e9 ont pris\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Fr\u00e9d\u00e9ric EFFE\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.moyenagepassion.com\/index.php\/2017\/11\/08\/le-moyen-age-de-jacques-le-goff\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.moyenagepassion.com\\\/index.php\\\/2017\\\/11\\\/08\\\/le-moyen-age-de-jacques-le-goff\\\/#article\",\"name\":\"Le moyen-\\u00e2ge de jacques le Goff | Moyen \\u00c2ge Passion\",\"headline\":\"Le moyen-\\u00e2ge de jacques le Goff\",\"author\":{\"@id\":\"https:\\\/\\\/www.moyenagepassion.com\\\/index.php\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.moyenagepassion.com\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.moyenagepassion.com\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/citation_monde_medieval_jacques_le_goff_historien_medieviste_moyen-age_racines_modernite.jpg\",\"@id\":\"https:\\\/\\\/www.moyenagepassion.com\\\/index.php\\\/2017\\\/11\\\/08\\\/le-moyen-age-de-jacques-le-goff\\\/#articleImage\",\"width\":1280,\"height\":481},\"datePublished\":\"2017-11-08T02:00:18+01:00\",\"dateModified\":\"2020-10-05T01:21:26+01:00\",\"inLanguage\":\"fr-FR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.moyenagepassion.com\\\/index.php\\\/2017\\\/11\\\/08\\\/le-moyen-age-de-jacques-le-goff\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.moyenagepassion.com\\\/index.php\\\/2017\\\/11\\\/08\\\/le-moyen-age-de-jacques-le-goff\\\/#webpage\"},\"articleSection\":\"Citations m\\u00e9di\\u00e9vales ou sur le moyen-\\u00e2ge, citation, histoire m\\u00e9di\\u00e9vale, monde m\\u00e9di\\u00e9val, moyen age, Citation\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.moyenagepassion.com\\\/index.php\\\/2017\\\/11\\\/08\\\/le-moyen-age-de-jacques-le-goff\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.moyenagepassion.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.moyenagepassion.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.moyenagepassion.com\\\/index.php\\\/moyen-age\\\/citations-moyen-age-medievales\\\/#listItem\",\"name\":\"Citations m\\u00e9di\\u00e9vales ou sur le moyen-\\u00e2ge\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.moyenagepassion.com\\\/index.php\\\/moyen-age\\\/citations-moyen-age-medievales\\\/#listItem\",\"position\":2,\"name\":\"Citations m\\u00e9di\\u00e9vales ou sur le moyen-\\u00e2ge\",\"item\":\"https:\\\/\\\/www.moyenagepassion.com\\\/index.php\\\/moyen-age\\\/citations-moyen-age-medievales\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.moyenagepassion.com\\\/index.php\\\/2017\\\/11\\\/08\\\/le-moyen-age-de-jacques-le-goff\\\/#listItem\",\"name\":\"Le moyen-\\u00e2ge de jacques le Goff\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.moyenagepassion.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.moyenagepassion.com\\\/index.php\\\/2017\\\/11\\\/08\\\/le-moyen-age-de-jacques-le-goff\\\/#listItem\",\"position\":3,\"name\":\"Le moyen-\\u00e2ge de jacques le Goff\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.moyenagepassion.com\\\/index.php\\\/moyen-age\\\/citations-moyen-age-medievales\\\/#listItem\",\"name\":\"Citations m\\u00e9di\\u00e9vales ou sur le moyen-\\u00e2ge\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.moyenagepassion.com\\\/#person\",\"name\":\"Fr\\u00e9d\\u00e9ric EFFE\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.moyenagepassion.com\\\/index.php\\\/2017\\\/11\\\/08\\\/le-moyen-age-de-jacques-le-goff\\\/#personImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f057d115b98aa9f5e018eff478396402?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Fr\\u00e9d\\u00e9ric EFFE\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.moyenagepassion.com\\\/index.php\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/www.moyenagepassion.com\\\/index.php\\\/author\\\/admin\\\/\",\"name\":\"Fr\\u00e9d\\u00e9ric EFFE\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.moyenagepassion.com\\\/index.php\\\/2017\\\/11\\\/08\\\/le-moyen-age-de-jacques-le-goff\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f057d115b98aa9f5e018eff478396402?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Fr\\u00e9d\\u00e9ric EFFE\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.moyenagepassion.com\\\/index.php\\\/2017\\\/11\\\/08\\\/le-moyen-age-de-jacques-le-goff\\\/#webpage\",\"url\":\"https:\\\/\\\/www.moyenagepassion.com\\\/index.php\\\/2017\\\/11\\\/08\\\/le-moyen-age-de-jacques-le-goff\\\/\",\"name\":\"Le moyen-\\u00e2ge de jacques le Goff | Moyen \\u00c2ge Passion\",\"description\":\"Sujet : citations, monde m\\u00e9di\\u00e9val, moyen-\\u00e2ge, Histoire m\\u00e9di\\u00e9vale. Auteur : Jacques le Goff (1924-2014), historien m\\u00e9di\\u00e9viste. \\u201cLe Moyen Age a \\u00e9t\\u00e9 un grand laboratoire d'id\\u00e9es, d'institutions, de formes, et il reste une mine d'enseignements. Il vient certes apr\\u00e8s l'Antiquit\\u00e9, si riche, si florissante. Pourtant, malgr\\u00e9 les progr\\u00e8s de l'histoire ancienne, les civilisations du pass\\u00e9 ont pris\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.moyenagepassion.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.moyenagepassion.com\\\/index.php\\\/2017\\\/11\\\/08\\\/le-moyen-age-de-jacques-le-goff\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.moyenagepassion.com\\\/index.php\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.moyenagepassion.com\\\/index.php\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2017-11-08T02:00:18+01:00\",\"dateModified\":\"2020-10-05T01:21:26+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.moyenagepassion.com\\\/#website\",\"url\":\"https:\\\/\\\/www.moyenagepassion.com\\\/\",\"name\":\"Moyen \\u00c2ge Passion\",\"description\":\"Explorer le Monde M\\u00e9di\\u00e9val sous toutes ses formes\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.moyenagepassion.com\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Le moyen-\u00e2ge de jacques le Goff | Moyen \u00c2ge Passion<\/title>\n\n","aioseo_head_json":{"title":"Le moyen-\u00e2ge de jacques le Goff | Moyen \u00c2ge Passion","description":"Sujet : citations, monde m\u00e9di\u00e9val, moyen-\u00e2ge, Histoire m\u00e9di\u00e9vale. Auteur : Jacques le Goff (1924-2014), historien m\u00e9di\u00e9viste. \u201cLe Moyen Age a \u00e9t\u00e9 un grand laboratoire d'id\u00e9es, d'institutions, de formes, et il reste une mine d'enseignements. Il vient certes apr\u00e8s l'Antiquit\u00e9, si riche, si florissante. Pourtant, malgr\u00e9 les progr\u00e8s de l'histoire ancienne, les civilisations du pass\u00e9 ont pris","canonical_url":"https:\/\/www.moyenagepassion.com\/index.php\/2017\/11\/08\/le-moyen-age-de-jacques-le-goff\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.moyenagepassion.com\/index.php\/2017\/11\/08\/le-moyen-age-de-jacques-le-goff\/#article","name":"Le moyen-\u00e2ge de jacques le Goff | Moyen \u00c2ge Passion","headline":"Le moyen-\u00e2ge de jacques le Goff","author":{"@id":"https:\/\/www.moyenagepassion.com\/index.php\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/www.moyenagepassion.com\/#person"},"image":{"@type":"ImageObject","url":"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2017\/11\/citation_monde_medieval_jacques_le_goff_historien_medieviste_moyen-age_racines_modernite.jpg","@id":"https:\/\/www.moyenagepassion.com\/index.php\/2017\/11\/08\/le-moyen-age-de-jacques-le-goff\/#articleImage","width":1280,"height":481},"datePublished":"2017-11-08T02:00:18+01:00","dateModified":"2020-10-05T01:21:26+01:00","inLanguage":"fr-FR","mainEntityOfPage":{"@id":"https:\/\/www.moyenagepassion.com\/index.php\/2017\/11\/08\/le-moyen-age-de-jacques-le-goff\/#webpage"},"isPartOf":{"@id":"https:\/\/www.moyenagepassion.com\/index.php\/2017\/11\/08\/le-moyen-age-de-jacques-le-goff\/#webpage"},"articleSection":"Citations m\u00e9di\u00e9vales ou sur le moyen-\u00e2ge, citation, histoire m\u00e9di\u00e9vale, monde m\u00e9di\u00e9val, moyen age, Citation"},{"@type":"BreadcrumbList","@id":"https:\/\/www.moyenagepassion.com\/index.php\/2017\/11\/08\/le-moyen-age-de-jacques-le-goff\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.moyenagepassion.com#listItem","position":1,"name":"Home","item":"https:\/\/www.moyenagepassion.com","nextItem":{"@type":"ListItem","@id":"https:\/\/www.moyenagepassion.com\/index.php\/moyen-age\/citations-moyen-age-medievales\/#listItem","name":"Citations m\u00e9di\u00e9vales ou sur le moyen-\u00e2ge"}},{"@type":"ListItem","@id":"https:\/\/www.moyenagepassion.com\/index.php\/moyen-age\/citations-moyen-age-medievales\/#listItem","position":2,"name":"Citations m\u00e9di\u00e9vales ou sur le moyen-\u00e2ge","item":"https:\/\/www.moyenagepassion.com\/index.php\/moyen-age\/citations-moyen-age-medievales\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.moyenagepassion.com\/index.php\/2017\/11\/08\/le-moyen-age-de-jacques-le-goff\/#listItem","name":"Le moyen-\u00e2ge de jacques le Goff"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.moyenagepassion.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.moyenagepassion.com\/index.php\/2017\/11\/08\/le-moyen-age-de-jacques-le-goff\/#listItem","position":3,"name":"Le moyen-\u00e2ge de jacques le Goff","previousItem":{"@type":"ListItem","@id":"https:\/\/www.moyenagepassion.com\/index.php\/moyen-age\/citations-moyen-age-medievales\/#listItem","name":"Citations m\u00e9di\u00e9vales ou sur le moyen-\u00e2ge"}}]},{"@type":"Person","@id":"https:\/\/www.moyenagepassion.com\/#person","name":"Fr\u00e9d\u00e9ric EFFE","image":{"@type":"ImageObject","@id":"https:\/\/www.moyenagepassion.com\/index.php\/2017\/11\/08\/le-moyen-age-de-jacques-le-goff\/#personImage","url":"https:\/\/secure.gravatar.com\/avatar\/f057d115b98aa9f5e018eff478396402?s=96&d=mm&r=g","width":96,"height":96,"caption":"Fr\u00e9d\u00e9ric EFFE"}},{"@type":"Person","@id":"https:\/\/www.moyenagepassion.com\/index.php\/author\/admin\/#author","url":"https:\/\/www.moyenagepassion.com\/index.php\/author\/admin\/","name":"Fr\u00e9d\u00e9ric EFFE","image":{"@type":"ImageObject","@id":"https:\/\/www.moyenagepassion.com\/index.php\/2017\/11\/08\/le-moyen-age-de-jacques-le-goff\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/f057d115b98aa9f5e018eff478396402?s=96&d=mm&r=g","width":96,"height":96,"caption":"Fr\u00e9d\u00e9ric EFFE"}},{"@type":"WebPage","@id":"https:\/\/www.moyenagepassion.com\/index.php\/2017\/11\/08\/le-moyen-age-de-jacques-le-goff\/#webpage","url":"https:\/\/www.moyenagepassion.com\/index.php\/2017\/11\/08\/le-moyen-age-de-jacques-le-goff\/","name":"Le moyen-\u00e2ge de jacques le Goff | Moyen \u00c2ge Passion","description":"Sujet : citations, monde m\u00e9di\u00e9val, moyen-\u00e2ge, Histoire m\u00e9di\u00e9vale. Auteur : Jacques le Goff (1924-2014), historien m\u00e9di\u00e9viste. \u201cLe Moyen Age a \u00e9t\u00e9 un grand laboratoire d'id\u00e9es, d'institutions, de formes, et il reste une mine d'enseignements. Il vient certes apr\u00e8s l'Antiquit\u00e9, si riche, si florissante. Pourtant, malgr\u00e9 les progr\u00e8s de l'histoire ancienne, les civilisations du pass\u00e9 ont pris","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/www.moyenagepassion.com\/#website"},"breadcrumb":{"@id":"https:\/\/www.moyenagepassion.com\/index.php\/2017\/11\/08\/le-moyen-age-de-jacques-le-goff\/#breadcrumblist"},"author":{"@id":"https:\/\/www.moyenagepassion.com\/index.php\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.moyenagepassion.com\/index.php\/author\/admin\/#author"},"datePublished":"2017-11-08T02:00:18+01:00","dateModified":"2020-10-05T01:21:26+01:00"},{"@type":"WebSite","@id":"https:\/\/www.moyenagepassion.com\/#website","url":"https:\/\/www.moyenagepassion.com\/","name":"Moyen \u00c2ge Passion","description":"Explorer le Monde M\u00e9di\u00e9val sous toutes ses formes","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/www.moyenagepassion.com\/#person"}}]}},"aioseo_meta_data":{"post_id":"16844","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-13 05:48:04","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2020-12-21 17:37:43","updated":"2026-05-13 05:48:04"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.moyenagepassion.com\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.moyenagepassion.com\/index.php\/moyen-age\/citations-moyen-age-medievales\/\" title=\"Citations m\u00e9di\u00e9vales ou sur le moyen-\u00e2ge\">Citations m\u00e9di\u00e9vales ou sur le moyen-\u00e2ge<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tLe moyen-\u00e2ge de jacques le Goff\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.moyenagepassion.com"},{"label":"Citations m\u00e9di\u00e9vales ou sur le moyen-\u00e2ge","link":"https:\/\/www.moyenagepassion.com\/index.php\/moyen-age\/citations-moyen-age-medievales\/"},{"label":"Le moyen-\u00e2ge de jacques le Goff","link":"https:\/\/www.moyenagepassion.com\/index.php\/2017\/11\/08\/le-moyen-age-de-jacques-le-goff\/"}],"_links":{"self":[{"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/posts\/16844"}],"collection":[{"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/comments?post=16844"}],"version-history":[{"count":1,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/posts\/16844\/revisions"}],"predecessor-version":[{"id":34791,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/posts\/16844\/revisions\/34791"}],"wp:attachment":[{"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/media?parent=16844"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/categories?post=16844"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/tags?post=16844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}