{"id":28184,"date":"2019-08-24T22:49:58","date_gmt":"2019-08-24T21:49:58","guid":{"rendered":"https:\/\/www.moyenagepassion.com\/?p=28184"},"modified":"2022-06-02T05:04:34","modified_gmt":"2022-06-02T04:04:34","slug":"au-xve-siecle-le-mystere-de-la-passion-de-jean-michel-et-la-lecon-du-pecheur-zebedee-a-ses-deux-fils","status":"publish","type":"post","link":"https:\/\/www.moyenagepassion.com\/index.php\/2019\/08\/24\/au-xve-siecle-le-mystere-de-la-passion-de-jean-michel-et-la-lecon-du-pecheur-zebedee-a-ses-deux-fils\/","title":{"rendered":"Au XVe si\u00e8cle, le Myst\u00e8re de la Passion de Jean Michel et la le\u00e7on du p\u00eacheur Z\u00e9b\u00e9d\u00e9e \u00e0 ses deux fils"},"content":{"rendered":"<div id=\"moyen-454798095\" class=\"moyen-before-content moyen-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-3035390706780632\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-3035390706780632\" \ndata-ad-slot=\"\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><p><strong><a href=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2019\/08\/poesie-medievale-moyen-age-chretien-mystere-de-la-passion-Jean-michel-XVe-siecle.jpg\"><img decoding=\"async\" class=\"alignleft wp-image-28188\" src=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2019\/08\/poesie-medievale-moyen-age-chretien-mystere-de-la-passion-Jean-michel-XVe-siecle.jpg\" alt=\"poesie-medievale-moyen-age-chretien-mystere-de-la-passion-Jean-michel-XVe-siecle\" width=\"97\" height=\"136\" \/><\/a>Sujet :<\/strong> po\u00e9sie m\u00e9di\u00e9vale, nouveau testament, myst\u00e8re, valeurs chr\u00e9tiennes m\u00e9di\u00e9vales,\u00a0 auteur m\u00e9di\u00e9val, drame, th\u00e9\u00e2tre m\u00e9di\u00e9val, po\u00e9sie morale<br \/>\n<strong>P\u00e9riode<\/strong> : Moyen \u00c2ge tardif, XVe si\u00e8cle.<br \/>\n<b>\u0152uvre<\/b>\u00a0: Le Myst\u00e8re de la Passion (1486)<br \/>\n<strong>Auteur<\/strong> : Jean Michel (1435 -1501)<\/p>\n<p>Bonjour \u00e0 tous,<\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" class=\"alignleft size-full wp-image-23888\" src=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2018\/10\/D_lettrine_moyen_age_passion.jpg\" alt=\"D_lettrine_moyen_age_passion\" width=\"84\" height=\"103\" \/>at\u00e9 de 1458, le <strong><em>Myst\u00e8re de la Passion<\/em><\/strong> de <strong>Arnould Gr\u00e9ban<\/strong> fut un Myst\u00e8re chr\u00e9tien tr\u00e8s pris\u00e9\u00a0du Moyen-\u00e2ge tardif. On peut le trouver publi\u00e9, en 1878, par deux c\u00e9l\u00e8bres m\u00e9di\u00e9vistes du XIXe si\u00e8cle : <strong>Gaston Paris<\/strong> et <strong>Gaston Raynaud<\/strong>. Pourtant ce n&rsquo;est pas cette pi\u00e8ce originale qui nous int\u00e9resse, aujourd&rsquo;hui, mais sa version remani\u00e9e, quelques trente ans plus tard, vers la fin du XVe si\u00e8cle.<\/p>\n<h2>Le Myst\u00e8re de la Passion de Jean Michel<\/h2>\n<p style=\"text-align: justify;\">Publi\u00e9e pour la premi\u00e8re fois en 1486, la pi\u00e8ce en question porte le m\u00eame nom que celle qui l&rsquo;avait inspir\u00e9e. Elle est sign\u00e9e de la main d&rsquo;un grand dramaturge angevin du nom\u00a0de\u00a0<strong>Jean Michel<\/strong>. Si on doit, par ailleurs, \u00e0 ce m\u00eame auteur m\u00e9di\u00e9val, l&rsquo;\u00e9criture d&rsquo;un autre myst\u00e8re (celui de la R\u00e9surrection), sa r\u00e9\u00e9criture du <em><strong>Myst\u00e8re de la passion<\/strong><\/em> fut si heureuse et talentueuse qu&rsquo;elle en vint m\u00eame \u00e0 \u00e9clipser l&rsquo;\u0153uvre originale de <strong>Arnould Gr\u00e9ban.<\/strong><\/p>\n<p style=\"text-align: justify;\">C&rsquo;est donc de l&rsquo;\u0153uvre de <strong>Jean Michel<\/strong> que sont extraits les vers que nous partageons avec vous ici. La sc\u00e8ne est inspir\u00e9e du Nouveau Testament ; le vieux p\u00eacheur Z\u00e9b\u00e9d\u00e9e y donne \u00e0 ses deux fils, Jacques et Jean, une le\u00e7on de vie profonde. On se souvient que, selon les \u00e9vangiles, les deux jeunes gens deviendront bient\u00f4t deux grands ap\u00f4tres du Christ. Ce dernier en fera, en effet, des \u00ab\u00a0p\u00e9cheurs d&rsquo;hommes\u00a0\u00bb dans une autre sc\u00e8ne bien connue des \u00e9critures.<\/p>\n<p style=\"text-align: justify;\">Dans un style d&rsquo;une grande puret\u00e9, Jean Michel nous expose ici des valeurs qui sont au c\u0153ur du monde chr\u00e9tien m\u00e9di\u00e9val : humilit\u00e9, contentement, simplicit\u00e9. En prenant un peu de hauteur et au del\u00e0 de la r\u00e9f\u00e9rence biblique et purement chr\u00e9tienne, on pourra voir ici\u00a0 une le\u00e7on plus g\u00e9n\u00e9rale sur\u00a0le\u00a0sens de la vie.<\/p>\n<p><a href=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2019\/08\/poesie-medievale-mystere-de-la-passion-jean-michel-nouveau-testament-evangile-p\u00e9cheur-Zebedee-Moyen-Age-chretien.jpg\"><img decoding=\"async\" class=\"aligncenter wp-image-28189 size-full\" src=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2019\/08\/poesie-medievale-mystere-de-la-passion-jean-michel-nouveau-testament-evangile-p\u00e9cheur-Zebedee-Moyen-Age-chretien.jpg\" alt=\"poesie-medievale-mystere-de-la-passion-jean-michel-nouveau-testament-evangile-p\u00e9cheur-Zebedee-Moyen-Age-chretien\" width=\"560\" height=\"644\" srcset=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2019\/08\/poesie-medievale-mystere-de-la-passion-jean-michel-nouveau-testament-evangile-p\u00e9cheur-Zebedee-Moyen-Age-chretien.jpg 560w, https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2019\/08\/poesie-medievale-mystere-de-la-passion-jean-michel-nouveau-testament-evangile-p\u00e9cheur-Zebedee-Moyen-Age-chretien-261x300.jpg 261w\" sizes=\"(max-width: 560px) 100vw, 560px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Pour ceux que ce myst\u00e8re de la passion, au complet, int\u00e9resserait, sa version papier semble, pour l&rsquo;instant, assez difficile \u00e0 trouver. Le plus simple serait, sans doute, de miser sur une r\u00e9\u00e9dition\u00a0 d&rsquo;un ouvrage qui lui avait \u00e9t\u00e9 consacr\u00e9 en 1959. Le titre en est : <span class=\"fn\"><span dir=\"ltr\"><em>Le myst\u00e8re de la Passion (Angers 1486), \u00e9<\/em>dit\u00e9 par Omer Jodogne. Pour l&rsquo;instant, il ne semble pas disponible en ligne mais votre libraire pr\u00e9f\u00e9r\u00e9 saura, peut-\u00eatre, comment vous le procurer. Si ce n&rsquo;est pas le cas, il vous faudra vous contenter de sa version num\u00e9rique que vous pourrez emprunter pour quelques jours,\u00a0 sur le site archive.org.\u00a0<\/span><\/span>Vous trouverez, sinon, d&rsquo;autres extraits de ce <em>Myst\u00e8re de la Passion<\/em> selon <strong>Jean Michel<\/strong>\u00a0 (dont celui du jour),\u00a0 dans l&rsquo;ouvrage\u00a0<em>Morceaux choisis des auteurs fran\u00e7ais<\/em>, <em>po\u00e8tes et prosateurs<\/em>, de\u00a0<strong>Louis Petit de Julleville<\/strong>\u00a0(1901).<\/p>\n<p>Pour ce qui est de sa traduction, son moyen fran\u00e7ais ne pose pas de difficult\u00e9s particuli\u00e8res, aussi nous ne vous donnons ici que quelques menues clefs de vocabulaire.<\/p>\n<hr \/>\n<h3 style=\"text-align: center;\">La le\u00e7on du p\u00eacheur Z\u00e9b\u00e9d\u00e9e et ses deux fils<br \/>\nExtrait du Myst\u00e8re de la Passion de Jean Michel<\/h3>\n<p style=\"text-align: center;\"><span style=\"color: #008000;\"><em><strong>Mes enfans, congnoiss\u00e9s que c&rsquo;est<\/strong><\/em><\/span><br \/>\n<span style=\"color: #008000;\"><em><strong> De nostre povre vie humaine :<\/strong><\/em><\/span><br \/>\n<span style=\"color: #008000;\"><em><strong> En ce monde n&rsquo;a point d&rsquo;arrest,<\/strong><\/em><\/span><br \/>\n<span style=\"color: #008000;\"><em><strong> Le temps court ainsi qu&rsquo;il nous maine;<\/strong><\/em><\/span><br \/>\n<span style=\"color: #008000;\"><em><strong> Et qui quiert<\/strong><\/em><\/span><em>* (veut)<\/em><span style=\"color: #008000;\"><em><strong> richesse mondaine<\/strong><\/em><\/span><br \/>\n<span style=\"color: #008000;\"><em><strong> la fault gaigner loyaulment,<\/strong><\/em><\/span><br \/>\n<span style=\"color: #008000;\"><em><strong> Ou encourir d&rsquo;enfer la peine,<\/strong><\/em><\/span><br \/>\n<span style=\"color: #008000;\"><em><strong> A jamais perdurablement.<\/strong><\/em><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #008000;\"><em><strong>J&rsquo;ay en povre simplicit\u00e9<\/strong><\/em><\/span><br \/>\n<span style=\"color: #008000;\"><em><strong> Vescu sans avoir indigence;<\/strong><\/em><\/span><br \/>\n<span style=\"color: #008000;\"><em><strong> Je vy selon ma povret\u00e9 ;<\/strong><\/em><\/span><br \/>\n<span style=\"color: #008000;\"><em><strong> Si j&rsquo;ay petit, j&rsquo;ay patience.<\/strong><\/em><\/span><br \/>\n<span style=\"color: #008000;\"><em><strong> Mes enfans, j&rsquo;ay mis diligence<\/strong><\/em><\/span><br \/>\n<span style=\"color: #008000;\"><em><strong> A pecher et gaigner ma vie ;<\/strong><\/em><\/span><br \/>\n<span style=\"color: #008000;\"><em><strong> Ass\u00e9s a qui a suffisance.<\/strong><\/em><\/span><br \/>\n<span style=\"color: #008000;\"><em><strong> Des grans biens n&rsquo;ay je point envye.<\/strong><\/em><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #008000;\"><em><strong>Jehan et Jaque, or apren\u00e9s<\/strong><\/em><\/span><br \/>\n<span style=\"color: #008000;\"><em><strong> A congnoistre vent et mar\u00e9e;<\/strong><\/em><\/span><br \/>\n<span style=\"color: #008000;\"><em><strong> Si tous deulx mon mestier ten\u00e9s,<\/strong><\/em><\/span><br \/>\n<span style=\"color: #008000;\"><em><strong> Vous vivrez au jour la journ\u00e9e.<\/strong><\/em><\/span><br \/>\n<span style=\"color: #008000;\"><em><strong> Si vous avez bonne denr\u00e9e,<\/strong><\/em><\/span><br \/>\n<span style=\"color: #008000;\"><em><strong> Vend\u00e9s bien, et a juste pris,<\/strong><\/em><\/span><br \/>\n<span style=\"color: #008000;\"><em><strong> Et merci\u00e9s Dieu la vespr\u00e9e<\/strong><span style=\"color: #808080;\">* (au soir)<\/span><\/em><\/span><br \/>\n<span style=\"color: #008000;\"><em><strong> De tout ce que vous aur\u00e9s pris.<\/strong><\/em><\/span><\/p>\n<hr \/>\n<p>En vous souhaitant une tr\u00e8s belle journ\u00e9e.<\/p>\n<p>Fr\u00e9d\u00e9ric EFFE.<br \/>\nPour moyenagepassion.com<br \/>\nA la d\u00e9couverte du Moyen-Age sous toutes ses formes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sujet : po\u00e9sie m\u00e9di\u00e9vale, nouveau testament, myst\u00e8re, valeurs chr\u00e9tiennes m\u00e9di\u00e9vales,\u00a0 auteur m\u00e9di\u00e9val, drame, th\u00e9\u00e2tre m\u00e9di\u00e9val, po\u00e9sie morale P\u00e9riode : Moyen \u00c2ge tardif, XVe si\u00e8cle. \u0152uvre\u00a0: Le Myst\u00e8re de la Passion (1486) Auteur : Jean Michel (1435 -1501) Bonjour \u00e0 tous, at\u00e9 de 1458, le Myst\u00e8re de la Passion de Arnould Gr\u00e9ban fut un Myst\u00e8re chr\u00e9tien &hellip; <a href=\"https:\/\/www.moyenagepassion.com\/index.php\/2019\/08\/24\/au-xve-siecle-le-mystere-de-la-passion-de-jean-michel-et-la-lecon-du-pecheur-zebedee-a-ses-deux-fils\/\" class=\"more-link\">Continuer la lecture de <span class=\"screen-reader-text\">Au XVe si\u00e8cle, le Myst\u00e8re de la Passion de Jean Michel et la le\u00e7on du p\u00eacheur Z\u00e9b\u00e9d\u00e9e \u00e0 ses deux fils<\/span>  <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[4692,9],"tags":[728,4683,4688,4686,18,5587,5727,2747,4681,4685,4679,4680,615,1598,4684,4682,355,4687],"class_list":["post-28184","post","type-post","status-publish","format-standard","hentry","category-jean-michel","category-musique-medieval-historique-fantaisie-celtique","tag-auteur-medieval","tag-drame","tag-evangiles","tag-jean-michel","tag-moyen-age","tag-moyen-age-2","tag-moyen-age-tardif-3","tag-moyen-francais","tag-mystere","tag-mystere-chretien","tag-mystere-de-la-passion","tag-nouveau-testament","tag-poesie-medievale","tag-poesie-morale","tag-theatre-medieval","tag-valeurs-chretiennes-medievales","tag-xe-siecle","tag-zebedee"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/posts\/28184"}],"collection":[{"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/comments?post=28184"}],"version-history":[{"count":1,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/posts\/28184\/revisions"}],"predecessor-version":[{"id":44677,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/posts\/28184\/revisions\/44677"}],"wp:attachment":[{"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/media?parent=28184"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/categories?post=28184"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/tags?post=28184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}