{"id":28330,"date":"2019-08-31T01:15:17","date_gmt":"2019-08-31T00:15:17","guid":{"rendered":"https:\/\/www.moyenagepassion.com\/?p=28330"},"modified":"2022-06-02T05:19:06","modified_gmt":"2022-06-02T04:19:06","slug":"agenda-moyen-age-festif-les-21e-medievales-de-bouliac","status":"publish","type":"post","link":"https:\/\/www.moyenagepassion.com\/index.php\/2019\/08\/31\/agenda-moyen-age-festif-les-21e-medievales-de-bouliac\/","title":{"rendered":"Agenda moyen-\u00e2ge festif : les 21e M\u00e9di\u00e9vales de Bouliac"},"content":{"rendered":"<div id=\"moyen-871635613\" class=\"moyen-before-content moyen-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-3035390706780632\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-3035390706780632\" \ndata-ad-slot=\"\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><p><strong><a href=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2019\/08\/bouliac-ecu-armoirie-blason.jpg\"><img decoding=\"async\" class=\"alignleft wp-image-28331\" src=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2019\/08\/bouliac-ecu-armoirie-blason.jpg\" alt=\"bouliac-ecu-armoirie-blason\" width=\"104\" height=\"155\" srcset=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2019\/08\/bouliac-ecu-armoirie-blason.jpg 226w, https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2019\/08\/bouliac-ecu-armoirie-blason-201x300.jpg 201w\" sizes=\"(max-width: 104px) 100vw, 104px\" \/><\/a>Sujet<\/strong> : f\u00eate m\u00e9di\u00e9vale, animations, compagnies m\u00e9di\u00e9vales, Moyen \u00c2ge festif. agenda m\u00e9di\u00e9val, fauconnerie, campements, monde viking, archerie.<br \/>\n<strong>Ev\u00e9nement<\/strong> : les 21e m\u00e9di\u00e9vale de Bouliac<br \/>\n<strong>Lieu<\/strong>\u00a0: Bouliac,\u00a0Gironde, Nouvelle-Aquitaine<br \/>\n<strong>Dates<\/strong>\u00a0:\u00a0du\u00a06 au 9 septembre 2019<\/p>\n<p>Bonjour \u00e0 tous,<\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" class=\"alignleft size-full wp-image-23896\" src=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2018\/10\/L_lettrine_moyen_age_passion.jpg\" alt=\"L_lettrine_moyen_age_passion\" width=\"84\" height=\"103\" \/>a rentr\u00e9e scolaire n&rsquo;a pas encore tout \u00e0 fait pris le pas sur les r\u00e9jouissances et animations autour du Moyen \u00c2ge et, le week end prochain, ce sera au tour de Bouliac, en Gironde de f\u00eater ses m\u00e9di\u00e9vales.<\/p>\n<h2 style=\"text-align: justify;\">Au programme de ces m\u00e9di\u00e9vales<\/h2>\n<p style=\"text-align: justify;\">Organis\u00e9e par l&rsquo;<b class=\"\"><span class=\"Apple-style-span\" style=\"font-size: medium;\"><span class=\"Apple-style-span\"><i class=\"\">Association Amanieu de Bouliac, <\/i><\/span><\/span><\/b><span class=\"Apple-style-span\" style=\"font-size: medium;\"><span class=\"Apple-style-span\">on retrouvera, dans cette f\u00eate m\u00e9di\u00e9vale, de nombreuses troupes et animations pour en garantir le succ\u00e8s : musique, \u00e9chassiers et saltimbanques, th\u00e9\u00e2tre de rue, jeux pour grands et petits, ateliers de d\u00e9monstration de m\u00e9tiers du <img decoding=\"async\" class=\"alignright wp-image-28333\" src=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2019\/08\/medievales-bouliac-2019-gironde-nouvelle-aquitaine.jpg\" alt=\"medievales-bouliac-2019-gironde-nouvelle-aquitaine\" width=\"189\" height=\"267\" srcset=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2019\/08\/medievales-bouliac-2019-gironde-nouvelle-aquitaine.jpg 350w, https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2019\/08\/medievales-bouliac-2019-gironde-nouvelle-aquitaine-212x300.jpg 212w\" sizes=\"(max-width: 189px) 100vw, 189px\" \/>moyen-\u00e2ge et encore spectacle de fauconnerie. Du c\u00f4t\u00e9 des mesnies et combattants, deux camps d&rsquo;\u00e9poque seront install\u00e9s sur place : le premier pr\u00e9sentera l&rsquo;archerie du XIIIe si\u00e8cle.\u00a0Le second gravitera autour du monde viking et de ses redoutables guerriers.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\">Du point de vue programmation, la f\u00eate ouvrira, d\u00e8s le vendredi soir, avec un banquet spectacle pour battre son plein sur les deux jours du week-end jusqu&rsquo;au dimanche soir. Le samedi, elle fournira l&rsquo;occasion d&rsquo;une nocturne avec bal et spectacle de feu.<\/p>\n<h3>Compagnies m\u00e9di\u00e9vales, ateliers et intervenants<\/h3>\n<p style=\"text-align: justify;\"><span style=\"color: #008000;\"><em>Les Archers de Roland\u00a0 &#8211; BerserkrS\u00a0 &#8211; Vol en Sc\u00e8ne &#8211; Pescaluna &#8211; Celesti\u00e6s\u00a0 &#8211; Tan Elleil &#8211; Compagnie Via Cane\u00a0 &#8211; Compagnie Vrehnd &#8211; Compagnie K\u00e9ras &#8211; Lou Beret&rsquo;\u00a0 &#8211; Ludoth\u00e8que de Bouliac &#8211; A la Hache\u00a0 &#8211; Brins de couleurs &#8211; Association Scripta &#8211; La Trace du geste &#8211;\u00a0<span class=\"Apple-style-span\" style=\"font-size: medium;\"><span class=\"Apple-style-span\">Association Amanieu de Bouliac<\/span><\/span><\/em><\/span><\/p>\n<p style=\"text-align: justify;\">Nous vous laissons retrouver tous les d\u00e9tails de cette programmation ainsi que les informations de r\u00e9servation pour les banquets notamment sur les pages officielles de cette f\u00eate :<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.medievalesdebouliac.fr\/\" target=\"_blank\" rel=\"noopener noreferrer\">Site officiel <\/a>\u00a0&#8211; <a href=\"https:\/\/www.facebook.com\/MedievalesdeBouliac\" target=\"_blank\" rel=\"noopener noreferrer\">Facebook de l&rsquo;\u00e9v\u00e9nement<\/a><\/p>\n<p>Voir aussi\u00a0<a href=\"https:\/\/www.moyenagepassion.com\/index.php\/2018\/09\/06\/agenda-moyen-age-en-fete-et-animations-medievales-du-week-end\/\" target=\"_blank\" rel=\"noopener noreferrer\">Mention de la 20\u00e8me \u00e9dition de cette f\u00eate m\u00e9di\u00e9vale<\/a><\/p>\n<p>En vous souhaitant une belle journ\u00e9e.<br \/>\nFred<\/p>\n<p>Pour moyenagepassion.com<br \/>\n<em><strong>A la d\u00e9couverte du monde m\u00e9di\u00e9val sous toutes ses formes<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sujet : f\u00eate m\u00e9di\u00e9vale, animations, compagnies m\u00e9di\u00e9vales, Moyen \u00c2ge festif. agenda m\u00e9di\u00e9val, fauconnerie, campements, monde viking, archerie. Ev\u00e9nement : les 21e m\u00e9di\u00e9vale de Bouliac Lieu\u00a0: Bouliac,\u00a0Gironde, Nouvelle-Aquitaine Dates\u00a0:\u00a0du\u00a06 au 9 septembre 2019 Bonjour \u00e0 tous, a rentr\u00e9e scolaire n&rsquo;a pas encore tout \u00e0 fait pris le pas sur les r\u00e9jouissances et animations autour du Moyen &hellip; <a href=\"https:\/\/www.moyenagepassion.com\/index.php\/2019\/08\/31\/agenda-moyen-age-festif-les-21e-medievales-de-bouliac\/\" class=\"more-link\">Continuer la lecture de <span class=\"screen-reader-text\">Agenda moyen-\u00e2ge festif : les 21e M\u00e9di\u00e9vales de Bouliac<\/span>  <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[11],"tags":[1539,2529,4030,212,2743,4700,3938],"class_list":["post-28330","post","type-post","status-publish","format-standard","hentry","category-fetes-medievales-evenement","tag-agenda-medieval","tag-animations-medievales","tag-bouliac","tag-compagnies-medievales","tag-fauconnerie","tag-gironde","tag-nouvelle-aquitaine"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/posts\/28330"}],"collection":[{"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/comments?post=28330"}],"version-history":[{"count":1,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/posts\/28330\/revisions"}],"predecessor-version":[{"id":44689,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/posts\/28330\/revisions\/44689"}],"wp:attachment":[{"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/media?parent=28330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/categories?post=28330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/tags?post=28330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}