{"id":3384,"date":"2016-04-15T22:45:23","date_gmt":"2016-04-15T21:45:23","guid":{"rendered":"http:\/\/www.moyenagepassion.com\/?p=3384"},"modified":"2020-10-04T19:57:31","modified_gmt":"2020-10-04T18:57:31","slug":"une-vie-une-oeuvre-autour-de-francois-villon","status":"publish","type":"post","link":"https:\/\/www.moyenagepassion.com\/index.php\/2016\/04\/15\/une-vie-une-oeuvre-autour-de-francois-villon\/","title":{"rendered":"Une vie, une oeuvre, autour de Fran\u00e7ois Villon"},"content":{"rendered":"<div id=\"moyen-1881075389\" class=\"moyen-before-content moyen-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-3035390706780632\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-3035390706780632\" \ndata-ad-slot=\"\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><p><a href=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2016\/04\/francois_villon_le_lais_poesie_medievale_moyen-age_passion.jpg\"><img decoding=\"async\" class=\"alignnone size-full wp-image-3391\" src=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2016\/04\/francois_villon_le_lais_poesie_medievale_moyen-age_passion.jpg\" alt=\"francois_villon_le_lais_poesie_medievale_moyen-age_passion\" width=\"2454\" height=\"897\" \/><\/a><\/p>\n<p><strong>Sujet :<\/strong>\u00a0po\u00e9sie m\u00e9di\u00e9vale, po\u00e9sie satirique<br \/>\n<strong>Auteur :<\/strong> Fran\u00e7ois Villon<br \/>\n<strong>P\u00e9riode : <\/strong>moyen-\u00e2ge tardif, \u00a0XVe si\u00e8cle<strong><br \/>\nTitre :<\/strong> \u00ab\u00a0une vie, une oeuvre : Fran\u00e7ois Villon\u00a0\u00bb<br \/>\n<strong>M\u00e9dia :<\/strong>\u00a0\u00e9mission de Radio, \u00a0France Culture<br \/>\n<strong>Invit\u00e9s :<\/strong> Michel Zink, David Mus,\u00a0Frank Venaille<\/p>\n<p><span style=\"color: #008000;\"><em><strong>\u00ab\u00a0En ce temps que j&rsquo;ay dit devant,<\/strong><\/em><\/span><br \/>\n<span style=\"color: #008000;\"><em><strong>Sur No\u00ebl, morte saison,<\/strong><\/em><\/span><br \/>\n<span style=\"color: #008000;\"><em><strong>Que les loups se vivent du vent<\/strong><\/em><\/span><br \/>\n<span style=\"color: #008000;\"><em><strong>Et qu&rsquo;on se tient en sa maison,<\/strong><\/em><\/span><br \/>\n<span style=\"color: #008000;\"><em><strong>pour le frimas, pres du tyson,<\/strong><\/em><\/span><br \/>\n<span style=\"color: #008000;\"><em><strong>Me vint ung vouloir de briser<\/strong><\/em><\/span><br \/>\n<span style=\"color: #008000;\"><em><strong>La tres amoureuse prison<\/strong><\/em><\/span><br \/>\n<span style=\"color: #008000;\"><em><strong>Qui souloit mon cueur debriser.\u00a0\u00bb<br \/>\n<\/strong><\/em><span style=\"color: #000000;\">Fran\u00e7ois Villon, \u00ab\u00a0Le lais\u00a0\u00bb, extrait<em><strong>\u00a0.<\/strong><\/em><\/span><\/span><\/p>\n<p>Bonjour \u00e0 tous,<\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" class=\"alignleft size-full wp-image-128\" src=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2015\/12\/S_lettrine_moyen_age_passion.jpg\" alt=\"S_lettrine_moyen_age_passion\" width=\"84\" height=\"103\" \/>i vous aimez Fran\u00e7ois Villon ou si vous \u00eates simplement curieux de sa po\u00e9sie, cette tr\u00e8s bonne et tr\u00e8s s\u00e9rieuse \u00e9mission de radio, diffus\u00e9e il y a quelques temps d\u00e9j\u00e0 sur France Culture est faite pour vous. Elle r\u00e9unit, en effet, un po\u00e8te des temps modernes et deux \u00e9rudits autour de textes et de lecture du mythique po\u00e8te m\u00e9di\u00e9val.<\/p>\n<p><iframe src=\"https:\/\/www.youtube.com\/embed\/Ldu1Znp8jpE\" width=\"600\" height=\"338\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Une bonne \u00e9coute et une excellente journ\u00e9e!<\/p>\n<p>Fred<br \/>\nPour \u00a0moyenagepassion.com<br \/>\n<em><strong>\u00ab\u00a0A la d\u00e9couverte du monde m\u00e9di\u00e9val sous toutes ses formes\u00a0\u00bb<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sujet :\u00a0po\u00e9sie m\u00e9di\u00e9vale, po\u00e9sie satirique Auteur : Fran\u00e7ois Villon P\u00e9riode : moyen-\u00e2ge tardif, \u00a0XVe si\u00e8cle Titre : \u00ab\u00a0une vie, une oeuvre : Fran\u00e7ois Villon\u00a0\u00bb M\u00e9dia :\u00a0\u00e9mission de Radio, \u00a0France Culture Invit\u00e9s : Michel Zink, David Mus,\u00a0Frank Venaille \u00ab\u00a0En ce temps que j&rsquo;ay dit devant, Sur No\u00ebl, morte saison, Que les loups se vivent du vent &hellip; <a href=\"https:\/\/www.moyenagepassion.com\/index.php\/2016\/04\/15\/une-vie-une-oeuvre-autour-de-francois-villon\/\" class=\"more-link\">Continuer la lecture de <span class=\"screen-reader-text\">Une vie, une oeuvre, autour de Fran\u00e7ois Villon<\/span>  <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7,1318,9],"tags":[957,958,959,77,960,22,663,18,913,80,615,688,294,622,777],"class_list":["post-3384","post","type-post","status-publish","format-standard","hentry","category-documentaire-moyen-age-historique","category-francois-villon","category-musique-medieval-historique-fantaisie-celtique","tag-david-mus","tag-emission-radio","tag-france-culture","tag-francois-villon","tag-le-lais","tag-medievale","tag-michel-zink","tag-moyen-age","tag-moyen-age-tardif","tag-poesie","tag-poesie-medievale","tag-poesie-satirique","tag-poete","tag-poete-medieval","tag-villon"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/posts\/3384"}],"collection":[{"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/comments?post=3384"}],"version-history":[{"count":1,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/posts\/3384\/revisions"}],"predecessor-version":[{"id":34593,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/posts\/3384\/revisions\/34593"}],"wp:attachment":[{"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/media?parent=3384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/categories?post=3384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/tags?post=3384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}