{"id":45105,"date":"2022-07-05T03:43:51","date_gmt":"2022-07-05T02:43:51","guid":{"rendered":"https:\/\/www.moyenagepassion.com\/?p=45105"},"modified":"2022-08-01T03:04:55","modified_gmt":"2022-08-01T02:04:55","slug":"la-complainte-du-pauvre-commun-et-des-pauvres-laboureurs-de-france-2","status":"publish","type":"post","link":"https:\/\/www.moyenagepassion.com\/index.php\/2022\/07\/05\/la-complainte-du-pauvre-commun-et-des-pauvres-laboureurs-de-france-2\/","title":{"rendered":"la complainte du pauvre commun et des pauvres laboureurs de france (2)"},"content":{"rendered":"<div id=\"moyen-2022171728\" class=\"moyen-before-content moyen-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-3035390706780632\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-3035390706780632\" \ndata-ad-slot=\"\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2019\/02\/poesie_satirique_medievale_chroniques_historique_Enguerrand-De-Monstrelet_moyen-age-tardif.jpg\" alt=\"Portrait Enguerrand de Monstrelet\" class=\"wp-image-25483\" width=\"155\" height=\"228\"\/><\/figure><\/div>\n\n\n\n<p><strong>Sujet<\/strong>&nbsp;: complainte, po\u00e9sie m\u00e9di\u00e9vale, po\u00e9sie satirique, guerre de cent ans,&nbsp; moyen-Fran\u00e7ais, mis\u00e8re, laboureurs, \u00e9corcheurs, routiers.<br><strong>P\u00e9riode<\/strong>&nbsp;: Moyen \u00c2ge tardif,&nbsp; XVe si\u00e8cle.<br><strong>Titre<\/strong>&nbsp;:&nbsp;<em>Complainte du pauvre commun et des pauvres laboureurs de France<\/em><br><strong>Auteur<\/strong>&nbsp;: anonyme<br><strong>Ouvrage<\/strong>&nbsp;:&nbsp;<em>Les chroniques d\u2019Enguerrand de Monstrelet, (<\/em>1400-1444<em>)<\/em><\/p>\n\n\n\n<p>Bonjour \u00e0 tous,<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img decoding=\"async\" width=\"84\" height=\"103\" src=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2018\/10\/D_lettrine_moyen_age_passion.jpg\" alt=\"\" class=\"wp-image-23888\"\/><\/figure><\/div>\n\n\n\n<p class=\"classe text_justify\">ans le courant du Moyen \u00c2ge tardif,  <em>Enguerrand de Monstrelet<\/em>, auteur et chroniqueur picard, acquis \u00e0 la cause bourguignonne nous a laiss\u00e9 des chroniques sur les luttes intestines qui agitent la France de son temps et sur l&rsquo;in\u00e9vitable guerre de cent ans. <br><br>Nous sommes dans la premi\u00e8re moiti\u00e9 du XVe si\u00e8cle (1400-1444) et le chroniqueur m\u00e9di\u00e9val entend succ\u00e9der \u00e0 l&rsquo;\u0153uvre de Froissart. Le destin, pas plus que la post\u00e9rit\u00e9, ne lui pr\u00eateront le talent de plume de son pr\u00e9d\u00e9cesseur mais son \u0153uvre demeurera, quoi qu&rsquo;il en soit, une t\u00e9moignage de r\u00e9f\u00e9rence utile pour cette p\u00e9riode. Aujourd&rsquo;hui, nous continuons de nous int\u00e9resser \u00e0 une complainte populaire que l&rsquo;on retrouve cit\u00e9e dans ses chroniques historiques sous le titre : \u00ab\u00a0<em>la complainte du pauvre commun et des pauvres laboureurs de France<\/em>\u00ab\u00a0. <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2022\/07\/complainte-laboureurs-pauvre-commun-petit-peuple-Moyen-Age-moyen-francais-XVe-siecle.jpg\"><img decoding=\"async\" src=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2022\/07\/complainte-laboureurs-pauvre-commun-petit-peuple-Moyen-Age-moyen-francais-XVe-siecle-s.jpg\" alt=\"complainte du pauvre commun - extrait avec enluminure\" class=\"wp-image-45125\" width=\"650\" height=\"759\" srcset=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2022\/07\/complainte-laboureurs-pauvre-commun-petit-peuple-Moyen-Age-moyen-francais-XVe-siecle-s.jpg 650w, https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2022\/07\/complainte-laboureurs-pauvre-commun-petit-peuple-Moyen-Age-moyen-francais-XVe-siecle-s-257x300.jpg 257w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/a><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Complainte sur les dommages collat\u00e9raux <br>de la guerre et les exactions des \u00e9corcheurs<\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2022\/07\/deco-ecorcheurs-pilleurs-medievaux.jpg\" alt=\"\" class=\"wp-image-45143\" width=\"86\" height=\"371\"\/><\/figure><\/div>\n\n\n\n<p class=\"classe text_justify\">Pendant la guerre de cent ans, les campagnes souffrirent et s&rsquo;enflamm\u00e8rent plus d&rsquo;une fois sous la pression des dommages collat\u00e9raux de la guerre et des exactions  : pillages, disette, compagnies de routiers, de mercenaires ou d&rsquo;\u00e9corcheurs qui errent, sans solde, \u00e0 la tra\u00eene des batailles et qui se payent en ran\u00e7onnant ce qu&rsquo;il trouve sur leur passage. Bien souvent, le petit peuple subit tout cela, impuissant, jusqu&rsquo;\u00e0 ce que la mis\u00e8re gronde trop fort et finisse par engendrer des d\u00e9bordements g\u00e9n\u00e9ralement r\u00e9prim\u00e9s dans la violence. <\/p>\n\n\n\n<p class=\"classe text_justify\"><em>La<\/em> <em>Complainte du pauvre commun et des pauvres laboureurs de France<\/em>  t\u00e9moigne du sort fait au petit peuple dans les p\u00e9riodes les plus difficiles. Ce dernier y exprime sa r\u00e9volte contre les conflits nobiliaires et les pouvoirs dont il finit toujours par devenir l&rsquo;otage.  <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Auteur et attribution de cette complainte<\/h3>\n\n\n\n<p class=\"classe text_justify\">Dans ses chroniques, <em>Enguerrand de Monstrelet<\/em> ne cite pas l&rsquo;auteur de cette complainte. Il ne la commente pas, non plus. Du point de vue de l&rsquo;attribution, on a pu quelquefois en pr\u00eater la paternit\u00e9 au chroniqueur lui-m\u00eame, m\u00eame s&rsquo;il ne la revendique pas. Le po\u00e8te <a href=\"https:\/\/www.moyenagepassion.com\/index.php\/moyen-age\/musique-medieval-historique-fantaisie-celtique\/alain-chartier\/\">Alain Chartier<\/a> a parfois \u00e9t\u00e9, lui aussi, d\u00e9sign\u00e9 comme un auteur possible de ce texte. Les deux pistes ne semblent toutefois pas les bonnes et la pi\u00e8ce a donc conserv\u00e9, jusque l\u00e0, son anonymat. <\/p>\n\n\n\n<p class=\"classe text_justify\">Du point de vue de sa datation, on la trouve rattach\u00e9e \u00e0 l&rsquo;ann\u00e9e 1422 dans l&rsquo;ouvrage de Monstrelet. Apr\u00e8s coup, certains historiens ont pu \u00e9mettre l&rsquo;hypoth\u00e8se que ce cri de d\u00e9tresse populaire avait pu \u00eatre bien ant\u00e9rieur \u00e0 la p\u00e9riode couverte par le chroniqueur m\u00e9di\u00e9val. Il est vrai qu&rsquo;on pourrait presque y lire les pr\u00e9mices  de la grande jacquerie  de 1358. Mais, l\u00e0 aussi, la piste est erron\u00e9e.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Un chartiste \u00e0 la rescousse de la datation<\/h3>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2022\/07\/deco-ecorcheurs-pilleurs-medievaux.jpg\" alt=\"\" class=\"wp-image-45143\" width=\"86\" height=\"371\"\/><\/figure><\/div>\n\n\n\n<p class=\"classe text_justify\">Pour clarifier la datation de cette complainte, il fallait bien l&rsquo;aide d&rsquo;un chartiste et on trouve, dans un ancien ouvrage de la biblioth\u00e8que de l&rsquo;Ecole des Chartes, un \u00e9clairage plut\u00f4t convaincant sign\u00e9 de la main de Jules Quicherat (1). <br><br>De mani\u00e8re plut\u00f4t cocasse, l&rsquo;explication du m\u00e9di\u00e9viste et arch\u00e9ologue pourrait rapprocher les confusions de datation autour de cette <em>Complainte du pauvre commun<\/em> des d\u00e9buts du film \u00ab\u00a0Brazil\u00a0\u00bb de Terry Gilliam, et notamment  du moment o\u00f9 un certain \u00ab\u00a0Archibald Buttle\u00a0\u00bb se trouve confondu avec un \u00ab\u00a0Archibald Tuttle\u00a0\u00bb,  par la pr\u00e9sence malencontreuse d&rsquo;un insecte sur la trajectoire d&rsquo;un caract\u00e8re de machine \u00e0 \u00e9crire.  En l&rsquo;occurrence, dans notre complainte et suivant l&rsquo;hypoth\u00e8se de Quicherat,  un certain \u00ab\u00a0Rodrigue\u00a0\u00bb plut\u00f4t c\u00e9l\u00e8bre se serait retrouv\u00e9 chang\u00e9, par une erreur de copiste, en un \u00ab\u00a0Todigues\u00a0\u00bb totalement inconnu au bataillon. Voici la strophe en question :<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p class=\"has-text-align-center\"><em>\u00ab\u00a0H\u00e9las ! sans plus vous dire h\u00e9las,<br>Comment peuvent penser cr\u00e9atures,<br>Qui bien advisent noz figures,<br>Et ont sens et entendement,<br>Et nous voyent nuds par les rues<br>Aux gel\u00e9es et aux froidures,<br>Nostre pauvre vie querant :<br>Car nous n&rsquo;avons plus rien vaillant,<br>Comme aucuns vueillent langaigez.<br>Ils s&rsquo;en sont tres mal informez ;<br>Car s&rsquo;ils pensoient bien en <strong>Todigues<\/strong><br>Et Esco\u00e7ois en leur complices,<br>Et \u00e9s yvers qui sont passez,<br>Et autres voyes fort obliques,<br>Dont tous estats nous sont reliques<br>Comme chacun nous a plusm\u00e9\u00a0\u00bb<\/em><\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p class=\"classe text_justify\">Concernant ce Rodrigue auquel la complainte se r\u00e9f\u00e8re d&rsquo;apr\u00e8s notre chartiste, il s&rsquo;agirait donc de Rodrigue de Villandrando,  seigneur d&rsquo;Ussel et comte de Ribadeo et de Valladolid. Durant la premi\u00e8re moiti\u00e9 de XVe si\u00e8cle, ce noble d&rsquo;origine espagnol se convertit en un mercenaire aussi ambitieux et ind\u00e9pendant que cruel, au service de Charles VII, et se fit craindre en France comme en Espagne. En 1432, il fut notamment \u00e0 la t\u00eate d&rsquo;une compagnie d&rsquo;\u00e9corcheurs qui effectua des razzias en Anjou puis en Touraine apr\u00e8s que les \u00e9cossais soient d\u00e9j\u00e0 pass\u00e9s par l\u00e0 pour saigner \u00e0 blanc les populations ayant l&rsquo;infortune de se trouver sur leur route. C&rsquo;est donc, vraisemblablement, d&rsquo;apr\u00e8s ces exactions qu&rsquo;il faut dater cette complainte puisqu&rsquo;elle fait r\u00e9f\u00e9rence \u00e0 la fois \u00e0 Rodrigue et aux \u00e9cossais. Post\u00e9rieure \u00e0 1432 donc et pas dat\u00e9e de 1422 comme la chronique le sugg\u00e8re et donc, plus sous Charles VII qu&rsquo;\u00e0 la fin du r\u00e8gne de Charles VI.<\/p>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\">La complainte du pauvre commun <br>et des pauvres laboureurs de France (2)<\/h2>\n\n\n\n<p class=\"has-text-align-center\"><em>H\u00e9las ! h\u00e9las ! h\u00e9las ! h\u00e9las !<br>Pr\u00e9lats , princes , et bons seigneurs ,<br>Bourgeois, marchans, et advocats,<br>Gens de mestiers grans et mineurs,<br>Gens d&rsquo;armes , et les trois estats ,<br>Qui vivez sur nous laboureurs ,<br>Confortez nous d&rsquo;aucun bon ayde ;<br>Vivre nous fault, c&rsquo;est le rem\u00e8de.<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center\">(&#8230; <a href=\"https:\/\/www.moyenagepassion.com\/index.php\/2019\/02\/25\/au-debut-du-xve-siecle-la-complainte-du-pauvre-commun-et-des-pauvres-laboureurs-de-france-1\/\">Retrouver la 1\u00e8re partie de cette complainte ici.<\/a> )<\/p>\n\n\n\n<p class=\"has-text-align-center\"><em><strong><span class=\"has-inline-color has-green-color\">H\u00e9las ! comment ces tailles grans,<br>Qu&rsquo;avez fait, passa quinze ans<br>Par chacun an trois fois ou deux,<br>Et des monnoyes<\/span><\/strong><span class=\"has-inline-color has-medium-gray-color\"> (monnaie) <\/span><strong><span class=\"has-inline-color has-green-color\">les tumbemens ,<br>Et les griefs de voz sergens<br>Ont bien noz vaches et nos boeufs<br>Amoindris, et tous nos chevaux,<br>Tant qu&rsquo;ils n&rsquo;y treuvent plus que prendre :<br>Mais, par J\u00e9sus, le roi des cieux,<br>Ne s\u00e7ay si vous en valiez mieux.<br>Pour ce vous prions \u00e0 joinctes mains,<br>Que nous pardonnez noz complains,<br>Et qu&rsquo;en hayne ne prenez pas,<br>Si nous crions ainsi, h\u00e9las !<br><br>H\u00e9las! pour Dieu, noz bons seigneurs,<br>Qui estes tes grans gouverneurs,<br>Et gouvernez tous nostre roy,<br>Que nous veuillez donner secours :<br>An roy pr\u00e9sentez noz clamours <\/span><\/strong><span class=\"has-inline-color has-medium-gray-color\">(plaintes, dol\u00e9ances)<\/span><strong><span class=\"has-inline-color has-green-color\">,<br>Et vous joingnez de bonne foy<br>A luy faire passer l&rsquo;octroy,<br>Que tant humblement requ\u00e9ron,<br>En nostre humble supplication.<br>Noz tr\u00e9s chers seigneurs vous s\u00e7avez<br>Que la clef du royaume tenez<br>Et que trestout <\/span><\/strong><span class=\"has-inline-color has-medium-gray-color\">(tout enti\u00e8rement)<\/span><strong><span class=\"has-inline-color has-green-color\"> ne gist qu&rsquo;en vous;<br>Et pour ce que plaise qu&rsquo;ayez<br>Regard \u00e0 noz grans povretez,<br>Et qu&rsquo;ayez mercy de nous.<br>Pour Dieu seigneurs, advisez vous,<br>Vous tous qui avez la puissance<br>De donner bonne cons\u00e9quence<br>Aux lettres qu&rsquo;envoyons au roy<br>Et aux estats qui sont \u00e0 soy,<br>Et aussi pourrez en tel cas<br>Nous garder de crier, h\u00e9las !<br><br>H\u00e9las ! ducs, et marquis et comtes.<br>Barons, chevaliers et vicomtes,<br>Et nobles qui chasteaux avez ,<br>Voz ayglantiers et voz ronces ;<br>Vos officiers et leurs pompes<br>Nous ont souvent fait espoucer,<br>A voz murs nous ont faict garder,<br>La nuict \u00e0 la pluye et au vent<br>Trestout le corps de nous tremblant :<br>Puis nous mettoient voz gens asseur<br>Qu&rsquo;avions dormy dessus les murs ,<br>Et noz robbes<\/span><\/strong><span class=\"has-inline-color has-medium-gray-color\"> (v\u00eatements) <\/span><strong><span class=\"has-inline-color has-green-color\">nous despouilloient<br>Par violence rudement ,<br>En nous mettant \u00e0 grands ran\u00e7ons ,<br>Frappans sur nous de gros bastons,<br>Puis que leur disions tout bas :<br>Mercy pour Dieu , h\u00e9las ! h\u00e9las!<br><br>H\u00e9las ! h\u00e9las ! encor&rsquo; n&rsquo;estiez<br>Vous pas contens, se plus n&rsquo;aviez<br>De nous puis qu&rsquo;estions batus :<br>Et que nous estions ran\u00e7onnez<br>A fin de venir aux escus ,<br>Que vous avez moult souvent eus ,<br>Disant : \u00ab\u00a0C&rsquo;est nostre droit demaine <\/span><\/strong><span class=\"has-inline-color has-medium-gray-color\">(droit seigneurial, domanial)<\/span><strong><span class=\"has-inline-color has-green-color\">.\u00a0\u00bb<br>Raison le voudrait \u00e0 grand&rsquo; peine :<br>L\u00e0 ne sont pas les fondemens<br>De vos terriens tenemens <\/span><\/strong><span class=\"has-inline-color has-medium-gray-color\">(possessions fonci\u00e8res)<\/span><strong><span class=\"has-inline-color has-green-color\">,<br>Ils sont bien autrement fondez<br>Si vous tr\u00e8s bien le s\u00e7aviez :<br>Mais je croy que n&rsquo;y tendez pas ;<br>Vous en pourriez bien dire , h\u00e9las !<br><br>H\u00e9las voulentiers nous teussions<br>De plus parler , si nous peussions,<br>De vous, ne de voz officiers.<br>Mang\u00e9 ils ont noz goretons <\/span><\/strong><span class=\"has-inline-color has-medium-gray-color\">(cochons de lait)<\/span><strong><span class=\"has-inline-color has-green-color\"> ,<br>Et noz brebis, et noz moutons :<br>Et de noz bleds faits voz garniers,<br>Puis faut \u00e0 leur sergent leur glene,<br>Au portier du bled pour sa peine :<br>Et puis faut pour chacun vaisseau <\/span><\/strong><span class=\"has-inline-color has-medium-gray-color\">(vase, r\u00e9cipient)<\/span><strong><span class=\"has-inline-color has-green-color\">,<br>Qui est mis dedans le chasteau,<br>Cinq sols pour vostre capitaine ,<br>Et un ou deux boisseaux d&rsquo;avoyne ,<br>Dont il fuit souvent grans amas :<br>Ne luy chault se crions h\u00e9las.<br><br>H\u00e9las! encore y a-il plus,<br>Qui moult souvent le cueur nous trouble ,<br>Quand le roy mect une ayde sus :<br>Il convient que le coup nous double ,<br>Vous nous en mettez en grand trouble :<br>Car il convient souventes fois ,<br>Que nous les payons par deux fois.<br>Et quand gens d&rsquo;armes au pays viennent ,<br>Qui de bien vous servir se peinent ,<br>Pource que vous les soustenez ,<br>Noz beufs , et noz vaches emmeinent<br>Et les tuent , et les detiennent :<br>Et s&rsquo;il est que les engardez ,<br>Il faut qu&rsquo;ayez pour voz peines<br>Et de l&rsquo;argent, et des avoynes ,<br>Et les mettent en un grand tas ;<br>Nous povons bien crier h\u00e9las.<br><br>H\u00e9las ! gens d&rsquo;armes et de traict  <\/span><\/strong><span class=\"has-inline-color has-medium-gray-color\">(archers, arbal\u00e9triers)<\/span><strong><span class=\"has-inline-color has-green-color\">,<br>Vous avez le forment <\/span><\/strong><span class=\"has-inline-color has-medium-gray-color\">(froment, vivres)<\/span><span class=\"has-inline-color has-green-color\" style=\"\"><b> deffaict  ,<br>Et mis en consommation ;<br>Tourmentez nous avez de fait,<br>Le complaindre peu nous vaudrait<br>Se plus avant en dision.<br>Chacun s\u00e7ait bien si nous menton,<br>Mais je croy, que vueillez ou non,<br>Qu&rsquo;avant que soit longue saison<br>Pass\u00e9e , dire je vous os,<br>Que vous nous voirrez en repos.<br>A l&rsquo;ayde de voz destin\u00e9es<\/b><\/span><\/em><span class=\"has-inline-color has-medium-gray-color\"> (<em>d\u00e9cisions<\/em><\/span><em><span class=\"has-inline-color has-medium-gray-color\">)<\/span><span class=\"has-inline-color has-green-color\" style=\"\"><b>,<br>Et de neiges , et de gel\u00e9es<br>Qui ont est\u00e9 en maints hyvers,<br>Maints <\/b><\/span><\/em><span class=\"has-inline-color has-medium-gray-color\">(nombre de nous)<\/span><em><span class=\"has-inline-color has-green-color\" style=\"\"><b> en cherront<\/b><\/span><span class=\"has-inline-color has-medium-gray-color\"> (de choir)<\/span><span class=\"has-inline-color has-green-color\" style=\"\"><b> trestous en vers,<br>Trestous morts la gueulle bayee<br>Avant que l&rsquo;ann\u00e9e soit pass\u00e9e,<br>Se Dieu n&rsquo;y employe sa gr\u00e2ce.<br>Ainsi lui plaise qu&rsquo;il le face,<br>Comme il feit aux Egyptiens<br>J\u00e0 pieca <\/b><\/span><span class=\"has-inline-color has-medium-gray-color\">(nagu\u00e8re)<\/span><span class=\"has-inline-color has-green-color\" style=\"\"><b> en l&rsquo;ancien temps,<br>Quand il les repeut <\/b><\/span><span class=\"has-inline-color has-medium-gray-color\">(nourrit)<\/span><span class=\"has-inline-color has-green-color\" style=\"\"><b> de la manne <\/b><\/span><span class=\"has-inline-color has-medium-gray-color\">(nourriture biblique durant l&rsquo;Exode)<\/span><span class=\"has-inline-color has-green-color\" style=\"\"><b>,<br>Qu&rsquo;il leur feit du ciel descendre,<br>De Pharaon les d\u00e9livra,<br>Ainsi que de nous il fera,<br>S&rsquo;il luy plaist,.ains Pasques fleuries<br>Si vous ne menez meilleur vie :<br>Et puis <\/b><\/span><strong><span class=\"has-inline-color has-green-color\">apr\u00e8s ne dirons pas,<br>Que nous faciez crier h\u00e9las !<\/span><\/strong><\/em><\/p>\n\n\n\n<p>En vous souhaitant une belle journ\u00e9e.<\/p>\n\n\n\n<p>Fred<br>Pour moyenagepassion.com<br><em><strong>A la d\u00e9couverte du Moyen-\u00e2ge sous toutes ses formes.<\/strong><\/em><\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p class=\"has-text-align-left\">Notes <\/p>\n\n\n\n<p class=\"classe text_justify has-small-font-size\">(1) <em>Rodrigue de Villandrando<\/em>, Jules Quicherat, Biblioth\u00e8que de l&rsquo;Ecole des Chartes, <em>revue d&rsquo;\u00e9rudition consacr\u00e9e principalement a l&rsquo;\u00e9tude du Moyen \u00c2ge<\/em> Tome Premier, 1844.<\/p>\n\n\n\n<p class=\"classe text_justify has-small-font-size\">NB : l&rsquo;enluminure utilis\u00e9e pour l&rsquo;illustration repr\u00e9sente des routiers s&rsquo;adonnant au pillage d&rsquo;un maison \u00e0 Paris. Elle est tir\u00e9e du  Royal 20  C VII : <em>Chroniques de France ou de St Denis<\/em>. Le manuscrit m\u00e9di\u00e9val dat\u00e9 de la fin du XIVe si\u00e8cle est actuellement conserv\u00e9 \u00e0 la British Library. <a href=\"https:\/\/www.bl.uk\/catalogues\/illuminatedmanuscripts\/record.asp?MSID=8466\">Vous pouvez le consulter ici<\/a>.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sujet&nbsp;: complainte, po\u00e9sie m\u00e9di\u00e9vale, po\u00e9sie satirique, guerre de cent ans,&nbsp; moyen-Fran\u00e7ais, mis\u00e8re, laboureurs, \u00e9corcheurs, routiers.P\u00e9riode&nbsp;: Moyen \u00c2ge tardif,&nbsp; XVe si\u00e8cle.Titre&nbsp;:&nbsp;Complainte du pauvre commun et des pauvres laboureurs de FranceAuteur&nbsp;: anonymeOuvrage&nbsp;:&nbsp;Les chroniques d\u2019Enguerrand de Monstrelet, (1400-1444) Bonjour \u00e0 tous, ans le courant du Moyen \u00c2ge tardif, Enguerrand de Monstrelet, auteur et chroniqueur picard, acquis \u00e0 la &hellip; <a href=\"https:\/\/www.moyenagepassion.com\/index.php\/2022\/07\/05\/la-complainte-du-pauvre-commun-et-des-pauvres-laboureurs-de-france-2\/\" class=\"more-link\">Continuer la lecture de <span class=\"screen-reader-text\">la complainte du pauvre commun et des pauvres laboureurs de france (2)<\/span>  <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":45123,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[4753,9],"tags":[5817,302,1481,5815,4342,2227,4173,1976,430,4803,5814,4196,5727,5195,5816,615,688,2168],"class_list":["post-45105","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-auteur-anonyme","category-musique-medieval-historique-fantaisie-celtique","tag-chroniques-historiques","tag-complainte","tag-ecole-des-chartes","tag-ecorcheurs","tag-enguerrand-de-monstrelet","tag-enluminures","tag-exactions","tag-guerre","tag-guerre-de-cent-ans","tag-jules-quicherat","tag-laboureurs","tag-misere","tag-moyen-age-tardif-3","tag-moyen-francais-2","tag-pillages","tag-poesie-medievale","tag-poesie-satirique","tag-xve-siecle"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/posts\/45105"}],"collection":[{"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/comments?post=45105"}],"version-history":[{"count":57,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/posts\/45105\/revisions"}],"predecessor-version":[{"id":45348,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/posts\/45105\/revisions\/45348"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/media\/45123"}],"wp:attachment":[{"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/media?parent=45105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/categories?post=45105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/tags?post=45105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}