{"id":819,"date":"2016-01-03T03:03:18","date_gmt":"2016-01-03T02:03:18","guid":{"rendered":"http:\/\/www.moyenagepassion.com\/?p=819"},"modified":"2020-10-04T19:58:38","modified_gmt":"2020-10-04T18:58:38","slug":"bestiaire-medieval-fantastique-les-elfes-sont-ils-des-incompris","status":"publish","type":"post","link":"https:\/\/www.moyenagepassion.com\/index.php\/2016\/01\/03\/bestiaire-medieval-fantastique-les-elfes-sont-ils-des-incompris\/","title":{"rendered":"Bestiaire m\u00e9di\u00e9val fantastique : la question \u00e9pineuse de l&rsquo;adaptation chez les elfes"},"content":{"rendered":"<div id=\"moyen-1353355823\" class=\"moyen-before-content moyen-entity-placement\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-3035390706780632\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-3035390706780632\" \ndata-ad-slot=\"\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div><figure id=\"attachment_821\" aria-describedby=\"caption-attachment-821\" style=\"width: 600px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2016\/01\/elfes_bestiaire_medieval_fantastique_moyen_age_passion.jpg\"><img decoding=\"async\" class=\"wp-image-821 size-full\" src=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2016\/01\/elfes_bestiaire_medieval_fantastique_moyen_age_passion.jpg\" alt=\"elfes_bestiaire_medieval_fantastique_moyen_age_passion\" width=\"600\" height=\"195\" srcset=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2016\/01\/elfes_bestiaire_medieval_fantastique_moyen_age_passion.jpg 600w, https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2016\/01\/elfes_bestiaire_medieval_fantastique_moyen_age_passion-300x98.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><figcaption id=\"caption-attachment-821\" class=\"wp-caption-text\">Les Elfes de JRR Tolkien, selon Peter Jackson dans Le Hobbit &amp; Le seigneur des anneaux<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><img decoding=\"async\" class=\"alignleft wp-image-445 size-full\" src=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2015\/12\/P_lettrine_moyen_age_passion-copia.jpg\" alt=\"P_lettrine_moyen_age_passion copia\" width=\"96\" height=\"103\" \/>oursuivons notre bestiaire m\u00e9di\u00e9val fantastique, en exclusivit\u00e9 pour moyenagepassion.com et pour nos lecteurs*, et, bien entendu, toujours\u00a0anim\u00e9s que nous sommes de la\u00a0volont\u00e9 tenace \u00a0de\u00a0mieux cerner tous ces \u00eatres magiques que l&rsquo;on peut pouvons croiser dans la litt\u00e9rature ou le cin\u00e9ma d\u00e9di\u00e9s au m\u00e9di\u00e9val fantaisie\u00a0(ou m\u00eame simplement dans une for\u00eat un peu ancienne pour certains d&rsquo;entre eux). Aujourd&rsquo;hui donc, nous parlons de ces merveilleuses cr\u00e9atures des for\u00eats que sont les elfes et nous nous posons la question de leur \u00ab\u00a0adaptabilit\u00e9 <img decoding=\"async\" class=\"alignright wp-image-830\" src=\"https:\/\/www.moyenagepassion.com\/wp-content\/uploads\/2016\/01\/moyen_age_bestiaire_medieval_fantastique_elfe_elrond.jpg\" alt=\"moyen_age_bestiaire_medieval_fantastique_elfe_elrond\" width=\"94\" height=\"105\" \/>sociale r\u00e9elle en environnement urbanis\u00e9 \u00e0 semi-urbanis\u00e9\u00a0\u00bb. Autrement dit, sans en faire des caisses non plus, il s&rsquo;agit de savoir comment les elfes\u00a0arrivent plus ou moins \u00e0 passer en ville, propos que nous t\u00e2cherons d&rsquo;illustrer \u00e0 travers une anecdote les concernant. <span style=\"color: #999999;\">(photo: Elrond, roi de elfes, Le\u00a0Seigneur des anneaux de\u00a0P. Jackson)<\/span><\/p>\n<p style=\"text-align: justify;\">Notre histoire se passe donc dans un village m\u00e9di\u00e9val. Trois elfes entrent dans une taverne et s&rsquo;assoient \u00e0 une table.\u00a0\u00a0La\u00a0patronne s&rsquo;approche et leur demande :<\/p>\n<p>\u00ab\u00a0&#8211; Qu&rsquo;est-ce qu&rsquo;on leur sert?\u00a0\u00bb<\/p>\n<p>Le premier elfe r\u00e9fl\u00e9chit longuement et finalement dit :<\/p>\n<p style=\"text-align: justify;\">\u00a0\u00bb &#8211; Je vais prendre un jus d&rsquo;airelles bien frais avec un soup\u00e7on de coulis de m\u00fbres et si c&rsquo;est possible, une \u00e0 deux pinc\u00e9es\u00a0de pollen de lys blanc, vraiment juste un peu par contre. Apr\u00e8s, sinon, \u00e7a va \u00eatre trop fort et \u00e7a va passer par dessus le go\u00fbt de la mure\u00a0\u00bb<\/p>\n<p>Le deuxi\u00e8me elfe se gratte la t\u00eate, et apr\u00e8s un moment, fait:<\/p>\n<p style=\"text-align: justify;\">\u00ab\u00a0&#8211; Alors, moi je vais plut\u00f4t partir sur un jus \u00e0 base de romarin et de tr\u00e8fles, avec un nuage d&rsquo;hydromel et, si vous avez, deux ou trois petites framboises sauvages \u00e9galement, mais par contre l\u00e0, vous vous emb\u00eatez pas, vous les mettez juste comme \u00e7a enti\u00e8res, avec le reste dans la chope\u00a0\u00bb.<\/p>\n<p>La patronne acquiesce et regarde le troisi\u00e8me elfe qui fait :<\/p>\n<p style=\"text-align: justify;\">\u00ab\u00a0&#8211; Bon du coup, moi, je vais partir sur un jus d&rsquo;airelles aussi, tr\u00e8s \u00a0bonne id\u00e9e \u00e7a Gw\u00ebh\u00ebndorn!, mais par contre ce qu&rsquo;on va faire, on va le couper avec un\u00a0bon tiers\u00a0de jus de cresson sauvage et trois cuill\u00e8res de miel d&rsquo;acacia. \u00c7a devrait le radoucir un peu. Ah aussi, si vous pouviez bien battre le tout pour que ce soit bien homog\u00e8ne, ce serait parfait\u00a0\u00bb.<\/p>\n<p>La femme acquiesce, retourne au comptoir o\u00f9 son mari, le tavernier, lui demande :<\/p>\n<p>\u00ab\u00a0&#8211; Alors, i veulent quoi?\u00a0\u00bb<\/p>\n<p>Et la femme lui r\u00e9pond :<\/p>\n<p>\u00ab\u00a0&#8211; Trois bi\u00e8res.\u00a0\u00bb<\/p>\n<p style=\"text-align: justify;\">___________________________________________________________________________<span style=\"color: #999999;\">PS : si vous avez un site web, une page sociale, un blog, une page FB et que vous souhaitez partager une partie des contenus \u00e9crits de notre\u00a0bestiaire m\u00e9di\u00e9val fantastique, <a href=\"https:\/\/www.moyenagepassion.com\/index.php\/contact\/\" target=\"_blank\" rel=\"noopener noreferrer\">merci de nous contacter avant<\/a>.\u00a0Ils sont tous originaux, d\u00e9pos\u00e9s et sous copyright et nous passons du temps \u00e0 les \u00e9crire avec notre petite main, cela\u00a0nous ferait donc plaisir d&rsquo;\u00eatre cr\u00e9dit\u00e9 de leur cr\u00e9ation.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>oursuivons notre bestiaire m\u00e9di\u00e9val fantastique, en exclusivit\u00e9 pour moyenagepassion.com et pour nos lecteurs*, et, bien entendu, toujours\u00a0anim\u00e9s que nous sommes de la\u00a0volont\u00e9 tenace \u00a0de\u00a0mieux cerner tous ces \u00eatres magiques que l&rsquo;on peut pouvons croiser dans la litt\u00e9rature ou le cin\u00e9ma d\u00e9di\u00e9s au m\u00e9di\u00e9val fantaisie\u00a0(ou m\u00eame simplement dans une for\u00eat un peu ancienne pour certains d&rsquo;entre &hellip; <a href=\"https:\/\/www.moyenagepassion.com\/index.php\/2016\/01\/03\/bestiaire-medieval-fantastique-les-elfes-sont-ils-des-incompris\/\" class=\"more-link\">Continuer la lecture de <span class=\"screen-reader-text\">Bestiaire m\u00e9di\u00e9val fantastique : la question \u00e9pineuse de l&rsquo;adaptation chez les elfes<\/span>  <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[8,1],"tags":[385,380,62,378,377,503,61,221,382,207,262,22,18,34,200,379,64,65,381],"class_list":["post-819","post","type-post","status-publish","format-standard","hentry","category-blagues-humour-moyen-age","category-moyen-age-passion","tag-bestiaire-medieval-fantastique","tag-biere","tag-blague","tag-elfe","tag-elfes","tag-fan-de-tolkien","tag-humour-medieval","tag-jrr-tolkien","tag-le-hobbit","tag-medieval-fantaisie","tag-medieval-fantastique","tag-medievale","tag-moyen-age","tag-passion","tag-peter-jackson","tag-seigneur-des-anneaux","tag-taverne","tag-tavernier","tag-village-medieval"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/posts\/819"}],"collection":[{"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/comments?post=819"}],"version-history":[{"count":1,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/posts\/819\/revisions"}],"predecessor-version":[{"id":34631,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/posts\/819\/revisions\/34631"}],"wp:attachment":[{"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/media?parent=819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/categories?post=819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.moyenagepassion.com\/index.php\/wp-json\/wp\/v2\/tags?post=819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}